{"id":60593,"date":"2025-07-25T11:02:59","date_gmt":"2025-07-25T11:02:59","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=60593"},"modified":"2025-07-25T11:02:59","modified_gmt":"2025-07-25T11:02:59","slug":"%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/sq\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/","title":{"rendered":"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438"},"content":{"rendered":"","protected":false},"featured_media":60612,"template":"","class_list":["post-60593","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0432\u043e-\u0432\u0435\u0432\u0447\u0430\u043d\u0438-\u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435-\u043e\u0431\u0443\u043a\u0430-\u0437\u0430-\u043f\u0440\u0435\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0432\u043e-\u0432\u0435\u0432\u0447\u0430\u043d\u0438-\u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435-\u043e\u0431\u0443\u043a\u0430-\u0437\u0430-\u043f\u0440\u0435\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/\",\"name\":\"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg\",\"datePublished\":\"2025-07-25T11:02:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/\u0432\u043e-\u0432\u0435\u0432\u0447\u0430\u043d\u0438-\u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435-\u043e\u0431\u0443\u043a\u0430-\u0437\u0430-\u043f\u0440\u0435\/","og_locale":"sq_AL","og_type":"article","og_title":"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/\u0432\u043e-\u0432\u0435\u0432\u0447\u0430\u043d\u0438-\u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435-\u043e\u0431\u0443\u043a\u0430-\u0437\u0430-\u043f\u0440\u0435\/","og_site_name":"Europe House","og_image":[{"width":2048,"height":1365,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/","name":"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg","datePublished":"2025-07-25T11:02:59+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/513907233_122247237560231225_2090922266572878612_n.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d0%b2%d0%be-%d0%b2%d0%b5%d0%b2%d1%87%d0%b0%d0%bd%d0%b8-%d0%be%d1%80%d0%b3%d0%b0%d0%bd%d0%b8%d0%b7%d0%b8%d1%80%d0%b0%d0%b2%d0%bc%d0%b5-%d0%be%d0%b1%d1%83%d0%ba%d0%b0-%d0%b7%d0%b0-%d0%bf%d1%80%d0%b5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"\u0412\u043e \u0412\u0435\u0432\u0447\u0430\u043d\u0438, \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0438\u0440\u0430\u0432\u043c\u0435 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u043f\u0440\u0435\u0432\u0435\u043d\u0446\u0438\u0458\u0430 \u0438 \u0441\u043f\u0440\u0435\u0447\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0448\u0443\u043c\u0441\u043a\u0438 \u043f\u043e\u0436\u0430\u0440\u0438, \u0432\u043e \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u0441\u043e \u0415\u043a\u043e-\u0441\u0432\u0435\u0441\u0442 \u0412\u0435\u0432\u0447\u0430\u043d\u0438"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/gallery\/60593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/media\/60612"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/media?parent=60593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}