{"id":59884,"date":"2025-06-27T20:20:30","date_gmt":"2025-06-27T20:20:30","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=59884"},"modified":"2025-06-27T20:20:30","modified_gmt":"2025-06-27T20:20:30","slug":"hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/sq\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/","title":{"rendered":"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e"},"content":{"rendered":"","protected":false},"featured_media":59888,"template":"","class_list":["post-59884","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-\u043f\u0440\u0432\u0438\u0442\u0435-\u0447\u0435\u043a\u043e\u0440\u0438-\u043a\u043e\u043d-\u0441\u0432\u0435\u0442\u043e\u0442-\u043d\u0430-\u043f\u0440\u043e\u0433\u0440\u0430\u043c\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-\u043f\u0440\u0432\u0438\u0442\u0435-\u0447\u0435\u043a\u043e\u0440\u0438-\u043a\u043e\u043d-\u0441\u0432\u0435\u0442\u043e\u0442-\u043d\u0430-\u043f\u0440\u043e\u0433\u0440\u0430\u043c\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/\",\"name\":\"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg\",\"datePublished\":\"2025-06-27T20:20:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg\",\"width\":1365,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-\u043f\u0440\u0432\u0438\u0442\u0435-\u0447\u0435\u043a\u043e\u0440\u0438-\u043a\u043e\u043d-\u0441\u0432\u0435\u0442\u043e\u0442-\u043d\u0430-\u043f\u0440\u043e\u0433\u0440\u0430\u043c\/","og_locale":"sq_AL","og_type":"article","og_title":"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-\u043f\u0440\u0432\u0438\u0442\u0435-\u0447\u0435\u043a\u043e\u0440\u0438-\u043a\u043e\u043d-\u0441\u0432\u0435\u0442\u043e\u0442-\u043d\u0430-\u043f\u0440\u043e\u0433\u0440\u0430\u043c\/","og_site_name":"Europe House","og_image":[{"width":1365,"height":2048,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/","name":"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg","datePublished":"2025-06-27T20:20:30+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/510551376_122241244274221654_6637237259010839049_n.jpg","width":1365,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/hour-of-code-%d0%bf%d1%80%d0%b2%d0%b8%d1%82%d0%b5-%d1%87%d0%b5%d0%ba%d0%be%d1%80%d0%b8-%d0%ba%d0%be%d0%bd-%d1%81%d0%b2%d0%b5%d1%82%d0%be%d1%82-%d0%bd%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Hour of Code: \u041f\u0440\u0432\u0438\u0442\u0435 \u0447\u0435\u043a\u043e\u0440\u0438 \u043a\u043e\u043d \u0441\u0432\u0435\u0442\u043e\u0442 \u043d\u0430 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438\u0440\u0430\u045a\u0435\u0442\u043e \u0438 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0430 \u0432\u043e \u0408\u0443\u0440\u043e\u043f \u0425\u0430\u0443\u0441 \u0422\u0430\u0435\u0442\u043e\u0432\u043e"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/gallery\/59884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/media\/59888"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/sq\/wp-json\/wp\/v2\/media?parent=59884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}