{"id":83,"date":"2020-01-18T13:37:15","date_gmt":"2020-01-18T13:37:15","guid":{"rendered":"http:\/\/superhost.com.mk\/euhouse\/?p=83"},"modified":"2020-09-09T13:01:32","modified_gmt":"2020-09-09T13:01:32","slug":"kids-movie-small-gangster","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/kids-movie-small-gangster\/","title":{"rendered":"Kids Movie &#8211; Small Gangster"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-83 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/79512717_2814301241965188_288932882477481984_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/79512717_2814301241965188_288932882477481984_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/79512717_2814301241965188_288932882477481984_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/79512717_2814301241965188_288932882477481984_o-300x225.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/79512717_2814301241965188_288932882477481984_o-768x576.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o-300x225.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o-768x576.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kids Movie - Small Gangster - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkkids-movie-small-gangster\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kids Movie - Small Gangster - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkkids-movie-small-gangster\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-18T13:37:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-09T13:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Kids Movie &#8211; Small Gangster\",\"datePublished\":\"2020-01-18T13:37:15+00:00\",\"dateModified\":\"2020-09-09T13:01:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/\"},\"wordCount\":11,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkkids-movie-small-gangster\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/\",\"url\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/\",\"name\":\"Kids Movie - Small Gangster - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\",\"datePublished\":\"2020-01-18T13:37:15+00:00\",\"dateModified\":\"2020-09-09T13:01:32+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkkids-movie-small-gangster\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kids Movie - Small Gangster - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkkids-movie-small-gangster\/","og_locale":"en_US","og_type":"article","og_title":"Kids Movie - Small Gangster - Europe House","og_url":"https:\/\/europehouse.mkkids-movie-small-gangster\/","og_site_name":"Europe House","article_published_time":"2020-01-18T13:37:15+00:00","article_modified_time":"2020-09-09T13:01:32+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Kids Movie &#8211; Small Gangster","datePublished":"2020-01-18T13:37:15+00:00","dateModified":"2020-09-09T13:01:32+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/"},"wordCount":11,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkkids-movie-small-gangster\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/","url":"https:\/\/europehouse.mkkids-movie-small-gangster\/","name":"Kids Movie - Small Gangster - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg","datePublished":"2020-01-18T13:37:15+00:00","dateModified":"2020-09-09T13:01:32+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkkids-movie-small-gangster\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkkids-movie-small-gangster\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/78971576_2814301048631874_5558882287522676736_o.jpg","width":1000,"height":750},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":6,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":1408,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/83\/revisions\/1408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}