{"id":765,"date":"2020-02-05T11:06:13","date_gmt":"2020-02-05T11:06:13","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=765"},"modified":"2020-02-11T11:08:01","modified_gmt":"2020-02-11T11:08:01","slug":"creative-europe-call-for-proposals-info-days","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/creative-europe-call-for-proposals-info-days\/","title":{"rendered":"Creative Europe Call for Proposals Info Days"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-765 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n-768x511.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0467.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0467.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0467.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0467-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0467-768x511.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0598.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0598.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0598.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0598-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/dsc_0598-768x511.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creative Europe Call for Proposals Info Days - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creative Europe Call for Proposals Info Days - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-05T11:06:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T11:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Creative Europe Call for Proposals Info Days\",\"datePublished\":\"2020-02-05T11:06:13+00:00\",\"dateModified\":\"2020-02-11T11:08:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\"},\"wordCount\":11,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\",\"url\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\",\"name\":\"Creative Europe Call for Proposals Info Days - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\",\"datePublished\":\"2020-02-05T11:06:13+00:00\",\"dateModified\":\"2020-02-11T11:08:01+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creative Europe Call for Proposals Info Days - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/","og_locale":"en_US","og_type":"article","og_title":"Creative Europe Call for Proposals Info Days - Europe House","og_url":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/","og_site_name":"Europe House","article_published_time":"2020-02-05T11:06:13+00:00","article_modified_time":"2020-02-11T11:08:01+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Creative Europe Call for Proposals Info Days","datePublished":"2020-02-05T11:06:13+00:00","dateModified":"2020-02-11T11:08:01+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/"},"wordCount":11,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/","url":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/","name":"Creative Europe Call for Proposals Info Days - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg","datePublished":"2020-02-05T11:06:13+00:00","dateModified":"2020-02-11T11:08:01+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkcreative-europe-call-for-proposals-info-days\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/02\/86185908_1415512148627172_6078040531055673344_n.jpg","width":1000,"height":666},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=765"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/765\/revisions"}],"predecessor-version":[{"id":775,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/765\/revisions\/775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/766"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}