{"id":5482,"date":"2022-04-14T10:56:14","date_gmt":"2022-04-14T10:56:14","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=5482"},"modified":"2024-07-25T08:21:06","modified_gmt":"2024-07-25T08:21:06","slug":"5482","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/5482\/","title":{"rendered":"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430"},"content":{"rendered":"<div dir=\"auto\">\u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438\u0442\u0435 \u043e\u0434 \u0410\u043b\u0433\u043e\u0440\u0438\u0442\u0430\u043c \u0433\u043e \u0438\u0441\u043f\u043e\u043b\u043d\u0438\u0458\u0430 \u043a\u0440\u0430\u0458\u043e\u0442 \u043d\u0430 \u0440\u0430\u0431\u043e\u0442\u043d\u0430\u0442\u0430 \u043d\u0435\u0434\u0435\u043b\u0430 \u0441\u043e \u043c\u043d\u043e\u0433\u0443 \u043a\u043e\u0440\u0438\u0441\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438:<\/div>\n<div dir=\"auto\">&#8211; \u0421\u0435 \u0434\u0440\u0443\u0436\u0435\u0430 \u0441\u043e \u0441\u0432\u043e\u0438\u0442\u0435 \u0432\u0440\u0441\u043d\u0438\u0446\u0438 \u043e\u0434 \u041d\u043e\u0432\u0438 \u0421\u0430\u0434 \u043f\u0440\u0435\u043a\u0443 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430\u0442\u0430 \u043d\u0430 <span class=\"nc684nl6\">Regional Youth Cooperation Office &#8211; RYCO<\/span> &#8211; Superschools<\/div>\n<div dir=\"auto\">&#8211; \u0408\u0430 \u043e\u0434\u0440\u0436\u0430\u0430 \u043f\u043e\u0441\u043b\u0435\u0434\u043d\u0430\u0442\u0430 \u043e\u0434 \u0441\u0435\u0440\u0438\u0458\u0430\u0442\u0430 \u0440\u0430\u0431\u043e\u0442\u0438\u043b\u043d\u0438\u0446\u0438 \u0437\u0430 \u0430\u0440\u0435\u043e\u0437\u0430\u0433\u0430\u0434\u0443\u0432\u0430\u045a\u0435\u0442\u043e \u0437\u0430\u0435\u0434\u043d\u043e \u0441\u043e <span class=\"nc684nl6\">Go Green &#8211; \u0411\u0438\u0434\u0438 \u0417\u0435\u043b\u0435\u043d<\/span> , \u0432\u043a\u043b\u0443\u0447\u0443\u0432\u0430\u0458\u045c\u0438 \u0433\u0438 \u0438 \u043f\u0440\u0438\u0458\u0430\u0442\u0435\u043b\u0438\u0442\u0435 \u043e\u0434 \u0421\u0440\u0431\u0438\u0458\u0430.<\/div>\n<div dir=\"auto\">&#8211; \u041f\u043e\u0434\u0435\u043b\u0438\u0458\u0430 \u0441\u0430\u0434\u043b\u0438\u0432\u0438 \u043a\u0430\u0440\u0442\u0438\u0447\u043a\u0438 \u0438 \u0440\u0430\u0447\u043d\u043e \u0438\u0437\u0440\u0430\u0431\u043e\u0442\u0435\u043d\u0438 \u043e\u0440\u0433\u0430\u043d\u0441\u043a\u0438 \u0441\u0430\u043f\u0443\u043d\u0438 \u043a\u043e\u0438 \u0441\u0430\u043c\u0438\u0442\u0435 \u0433\u0438 \u0438\u0437\u0440\u0430\u0431\u043e\u0442\u0438\u043b\u0435<\/div>\n<div dir=\"auto\">&#8211; \u041f\u0440\u043e\u0441\u043b\u0435\u0434\u0438\u0458\u0430 \u043e\u0431\u0443\u043a\u0430 \u0437\u0430 \u0431\u0435\u0437\u0431\u0435\u0434\u043d\u043e\u0441\u0442 \u0438 \u0441\u043f\u0430\u0441\u0443\u0432\u0430\u045a\u0435 \u0432\u043e \u0441\u043b\u0443\u0447\u0430\u0458 \u043d\u0430 \u0432\u0440\u0435\u043c\u0435\u043d\u0441\u043a\u0430 \u043d\u0435\u043f\u043e\u0433\u043e\u0434\u0430 \u043e\u0434 \u0441\u0442\u0440\u0443\u0447\u043d\u0438\u043e\u0442 \u0442\u0438\u043c \u043d\u0430 \u0426\u0440\u0432\u0435\u043d \u041a\u0440\u0441\u0442<\/div>\n<div dir=\"auto\">\u041f\u043e\u0433\u043b\u0435\u0434\u043d\u0435\u0442\u0435 \u0458\u0430 \u0430\u0442\u043c\u043e\u0441\u0444\u0435\u0440\u0430\u0442\u0430 \u0432\u043e \u0433\u0440\u0430\u0434\u0441\u043a\u0438\u043e\u0442 \u043f\u0430\u0440\u043a:<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5483\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7654-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7654-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7654-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7654-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7654.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5486\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7687-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7687-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7687-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7687-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7687.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5489\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7842-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7842-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7842-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7842-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7842.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5492\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7863-1024x644.jpg\" alt=\"\" width=\"1024\" height=\"644\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7863-1024x644.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7863-300x189.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7863-768x483.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7863.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5495\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7897-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7897-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7897-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7897-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7897.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5498\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_7990-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7990-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7990-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7990-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_7990.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5501\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8049-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8049-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8049-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8049-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8049.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5504\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8107-684x1024.jpg\" alt=\"\" width=\"684\" height=\"1024\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8107-684x1024.jpg 684w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8107-200x300.jpg 200w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8107-768x1151.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8107.jpg 801w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5507\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8133-1024x691.jpg\" alt=\"\" width=\"1024\" height=\"691\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133-1024x691.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133-300x203.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133-768x518.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5510\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8148-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8148-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8148-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8148-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8148.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5513\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8172-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8172-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8172-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8172-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8172.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5516\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8179-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8179-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8179-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8179-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8179.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-5519\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8190-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8190-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8190-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8190-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8190.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438\u0442\u0435 \u043e\u0434 \u0410\u043b\u0433\u043e\u0440\u0438\u0442\u0430\u043c \u0433\u043e \u0438\u0441\u043f\u043e\u043b\u043d\u0438\u0458\u0430 \u043a\u0440\u0430\u0458\u043e\u0442 \u043d\u0430 \u0440\u0430\u0431\u043e\u0442\u043d\u0430\u0442\u0430 \u043d\u0435\u0434\u0435\u043b\u0430 \u0441\u043e \u043c\u043d\u043e\u0433\u0443 \u043a\u043e\u0440\u0438\u0441\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438: &#8211; \u0421\u0435 \u0434\u0440\u0443\u0436\u0435\u0430 \u0441\u043e \u0441\u0432\u043e\u0438\u0442\u0435 \u0432\u0440\u0441\u043d\u0438\u0446\u0438 \u043e\u0434 \u041d\u043e\u0432\u0438 \u0421\u0430\u0434 \u043f\u0440\u0435\u043a\u0443 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430\u0442\u0430 \u043d\u0430 Regional Youth Cooperation Office &#8211; RYCO &#8211; Superschools &#8211; \u0408\u0430 \u043e\u0434\u0440\u0436\u0430\u0430 \u043f\u043e\u0441\u043b\u0435\u0434\u043d\u0430\u0442\u0430 \u043e\u0434 \u0441\u0435\u0440\u0438\u0458\u0430\u0442\u0430 \u0440\u0430\u0431\u043e\u0442\u0438\u043b\u043d\u0438\u0446\u0438 \u0437\u0430 \u0430\u0440\u0435\u043e\u0437\u0430\u0433\u0430\u0434\u0443\u0432\u0430\u045a\u0435\u0442\u043e \u0437\u0430\u0435\u0434\u043d\u043e \u0441\u043e Go Green &#8211; \u0411\u0438\u0434\u0438 \u0417\u0435\u043b\u0435\u043d , \u0432\u043a\u043b\u0443\u0447\u0443\u0432\u0430\u0458\u045c\u0438 \u0433\u0438 \u0438 \u043f\u0440\u0438\u0458\u0430\u0442\u0435\u043b\u0438\u0442\u0435 \u043e\u0434 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[193,194,195],"class_list":["post-5482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery","tag-algoritam","tag-highschools","tag-students"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk5482\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House\" \/>\n<meta property=\"og:description\" content=\"\u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438\u0442\u0435 \u043e\u0434 \u0410\u043b\u0433\u043e\u0440\u0438\u0442\u0430\u043c \u0433\u043e \u0438\u0441\u043f\u043e\u043b\u043d\u0438\u0458\u0430 \u043a\u0440\u0430\u0458\u043e\u0442 \u043d\u0430 \u0440\u0430\u0431\u043e\u0442\u043d\u0430\u0442\u0430 \u043d\u0435\u0434\u0435\u043b\u0430 \u0441\u043e \u043c\u043d\u043e\u0433\u0443 \u043a\u043e\u0440\u0438\u0441\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438: &#8211; \u0421\u0435 \u0434\u0440\u0443\u0436\u0435\u0430 \u0441\u043e \u0441\u0432\u043e\u0438\u0442\u0435 \u0432\u0440\u0441\u043d\u0438\u0446\u0438 \u043e\u0434 \u041d\u043e\u0432\u0438 \u0421\u0430\u0434 \u043f\u0440\u0435\u043a\u0443 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430\u0442\u0430 \u043d\u0430 Regional Youth Cooperation Office &#8211; RYCO &#8211; Superschools &#8211; \u0408\u0430 \u043e\u0434\u0440\u0436\u0430\u0430 \u043f\u043e\u0441\u043b\u0435\u0434\u043d\u0430\u0442\u0430 \u043e\u0434 \u0441\u0435\u0440\u0438\u0458\u0430\u0442\u0430 \u0440\u0430\u0431\u043e\u0442\u0438\u043b\u043d\u0438\u0446\u0438 \u0437\u0430 \u0430\u0440\u0435\u043e\u0437\u0430\u0433\u0430\u0434\u0443\u0432\u0430\u045a\u0435\u0442\u043e \u0437\u0430\u0435\u0434\u043d\u043e \u0441\u043e Go Green &#8211; \u0411\u0438\u0434\u0438 \u0417\u0435\u043b\u0435\u043d , \u0432\u043a\u043b\u0443\u0447\u0443\u0432\u0430\u0458\u045c\u0438 \u0433\u0438 \u0438 \u043f\u0440\u0438\u0458\u0430\u0442\u0435\u043b\u0438\u0442\u0435 \u043e\u0434 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk5482\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-14T10:56:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T08:21:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8133.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mk5482\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk5482\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430\",\"datePublished\":\"2022-04-14T10:56:14+00:00\",\"dateModified\":\"2024-07-25T08:21:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mk5482\/\"},\"wordCount\":97,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk5482\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg\",\"keywords\":[\"Algoritam\",\"highschools\",\"students\"],\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk5482\/\",\"url\":\"https:\/\/europehouse.mk5482\/\",\"name\":\"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk5482\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk5482\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg\",\"datePublished\":\"2022-04-14T10:56:14+00:00\",\"dateModified\":\"2024-07-25T08:21:06+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk5482\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk5482\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg\",\"width\":1200,\"height\":810},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk5482\/","og_locale":"en_US","og_type":"article","og_title":"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House","og_description":"\u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438\u0442\u0435 \u043e\u0434 \u0410\u043b\u0433\u043e\u0440\u0438\u0442\u0430\u043c \u0433\u043e \u0438\u0441\u043f\u043e\u043b\u043d\u0438\u0458\u0430 \u043a\u0440\u0430\u0458\u043e\u0442 \u043d\u0430 \u0440\u0430\u0431\u043e\u0442\u043d\u0430\u0442\u0430 \u043d\u0435\u0434\u0435\u043b\u0430 \u0441\u043e \u043c\u043d\u043e\u0433\u0443 \u043a\u043e\u0440\u0438\u0441\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438: &#8211; \u0421\u0435 \u0434\u0440\u0443\u0436\u0435\u0430 \u0441\u043e \u0441\u0432\u043e\u0438\u0442\u0435 \u0432\u0440\u0441\u043d\u0438\u0446\u0438 \u043e\u0434 \u041d\u043e\u0432\u0438 \u0421\u0430\u0434 \u043f\u0440\u0435\u043a\u0443 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0430\u0442\u0430 \u043d\u0430 Regional Youth Cooperation Office &#8211; RYCO &#8211; Superschools &#8211; \u0408\u0430 \u043e\u0434\u0440\u0436\u0430\u0430 \u043f\u043e\u0441\u043b\u0435\u0434\u043d\u0430\u0442\u0430 \u043e\u0434 \u0441\u0435\u0440\u0438\u0458\u0430\u0442\u0430 \u0440\u0430\u0431\u043e\u0442\u0438\u043b\u043d\u0438\u0446\u0438 \u0437\u0430 \u0430\u0440\u0435\u043e\u0437\u0430\u0433\u0430\u0434\u0443\u0432\u0430\u045a\u0435\u0442\u043e \u0437\u0430\u0435\u0434\u043d\u043e \u0441\u043e Go Green &#8211; \u0411\u0438\u0434\u0438 \u0417\u0435\u043b\u0435\u043d , \u0432\u043a\u043b\u0443\u0447\u0443\u0432\u0430\u0458\u045c\u0438 \u0433\u0438 \u0438 \u043f\u0440\u0438\u0458\u0430\u0442\u0435\u043b\u0438\u0442\u0435 \u043e\u0434 [&hellip;]","og_url":"https:\/\/europehouse.mk5482\/","og_site_name":"Europe House","article_published_time":"2022-04-14T10:56:14+00:00","article_modified_time":"2024-07-25T08:21:06+00:00","og_image":[{"width":1200,"height":810,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2022\/04\/dsc_8133.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mk5482\/#article","isPartOf":{"@id":"https:\/\/europehouse.mk5482\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430","datePublished":"2022-04-14T10:56:14+00:00","dateModified":"2024-07-25T08:21:06+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mk5482\/"},"wordCount":97,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mk5482\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg","keywords":["Algoritam","highschools","students"],"articleSection":["Media Gallery"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/europehouse.mk5482\/","url":"https:\/\/europehouse.mk5482\/","name":"Europe House \u0441\u043e \u0441\u0440\u0435\u0434\u043d\u0438\u0442\u0435 \u0443\u0447\u0438\u043b\u0438\u0448\u0442\u0430 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk5482\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk5482\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg","datePublished":"2022-04-14T10:56:14+00:00","dateModified":"2024-07-25T08:21:06+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk5482\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk5482\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2022\/04\/dsc_8133.jpg","width":1200,"height":810},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/5482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=5482"}],"version-history":[{"count":2,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/5482\/revisions"}],"predecessor-version":[{"id":5523,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/5482\/revisions\/5523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/5507"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=5482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=5482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=5482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}