{"id":4340,"date":"2021-12-03T11:57:24","date_gmt":"2021-12-03T11:57:24","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=4340"},"modified":"2021-12-03T11:57:24","modified_gmt":"2021-12-03T11:57:24","slug":"tamara-ristoska-invites-ilina-angelovska","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/tamara-ristoska-invites-ilina-angelovska\/","title":{"rendered":"Tamara Ristoska invites Ilina Angelovska"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/7a5B15Bpk9PG0pQaRQwfLp?utm_source=generator\" width=\"100%\" height=\"232\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\u0418\u043b\u0438\u043d\u0430 \u0410\u043d\u0433\u0435\u043b\u043e\u0432\u0441\u043a\u0430 \u0435 \u0434\u0438\u043f\u043b\u043e\u043c\u0438\u0440\u0430\u043d \u043b\u0438\u043a\u043e\u0432\u0435\u043d \u0443\u043c\u0435\u0442\u043d\u0438\u043a \u043d\u0430 \u0424\u0430\u043a\u0443\u043b\u0442\u0435\u0442\u043e\u0442 \u0437\u0430 \u043b\u0438\u043a\u043e\u0432\u043d\u0438 \u0443\u043c\u0435\u0442\u043d\u043e\u0441\u0442\u0438 \u0432\u043e \u0421\u043a\u043e\u043f\u0458\u0435.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\u041f\u043e\u0432\u0435\u045c\u0435 \u043e\u0434 15 \u0433\u043e\u0434\u0438\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e \u0441\u0435 \u0437\u0430\u043d\u0438\u043c\u0430\u0432\u0430 \u0441\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430 \u0438 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430, \u0432\u043e \u0441\u0444\u0435\u0440\u0430\u0442\u0430 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u043e\u0442 \u0438 \u0444\u0438\u043b\u043c\u043e\u0442, \u0430 \u043e\u0434 \u0408\u0430\u043d\u0443\u0430\u0440\u0438 2013 \u0433\u043e\u0434\u0438\u043d\u0430 \u0435 \u0432\u0440\u0430\u0431\u043e\u0442\u0435\u043d\u0430 \u0432\u043e \u041c\u0430\u043a\u0435\u0434\u043e\u043d\u0441\u043a\u0438\u043e\u0442 \u041d\u0430\u0440\u043e\u0434\u0435\u043d \u0422\u0435\u0430\u0442\u0430\u0440, \u043a\u0430\u043a\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\u0418\u043b\u0438\u043d\u0430 \u0438\u043c\u0430 \u0440\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u0430\u043d\u043e \u043f\u0440\u0435\u043a\u0443 50 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0438, \u043c\u0435\u0453\u0443 \u043a\u043e\u0438 \u0438 20\u0442\u0438\u043d\u0430 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0438. \u0414\u0435\u043b \u043e\u0434 \u043f\u0440\u0435\u0442\u0441\u0442\u0430\u0432\u0438\u0442\u0435 \u0432\u043e \u043a\u043e\u0438 \u0441\u0435 \u043f\u043e\u0442\u043f\u0438\u0448\u0443\u0432\u0430 \u043a\u0430\u043a\u043e \u0434\u0438\u0437\u0430\u0458\u043d\u0435\u0440 \u0441\u0435: \u041f\u0430\u0459\u0430\u0447\u0438 \u2013 \u041e\u043f\u0435\u0440\u0430, \u041c\u043e\u0458 \u0442\u0435\u0440\u043c\u0438\u043d, \u0426\u0440\u043d\u0438\u043b\u0430 \u0440\u0435\u043c\u0438\u043a\u0441, \u0410\u0432\u0430\u043d\u0442\u0443\u0440\u0438\u0442\u0435 \u043d\u0430 \u0410\u043b\u0430\u0434\u0438\u043d \u0438 \u043c\u043d\u043e\u0433\u0443 \u0434\u0440\u0443\u0433\u0438.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\u041a\u0430\u043a\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444 \u0438\u043b\u0438 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444 \u0438\u043c\u0430 \u0443\u0447\u0435\u0441\u0442\u0432\u0443\u0432\u0430\u043d\u043e \u0432\u043e \u043f\u043e\u0432\u0435\u045c\u0435 \u0438\u0433\u0440\u0430\u043d\u0438 \u0438 \u043a\u0440\u0430\u0442\u043a\u0438 \u0444\u0438\u043b\u043c\u043e\u0432\u0438 \u043a\u0430\u043a\u043e \u0438 \u0442\u0432 \u0441\u0435\u0440\u0438\u0438: \u201e\u041f\u0430\u043d\u043a\u043e\u0442 \u043d\u0435 \u0435 \u043c\u0440\u0442\u043e\u0432\u201c, \u201e\u0421\u043a\u043e\u043f\u0458\u0435 \u0440\u0435\u043c\u0438\u043a\u0441\u201c, \u201e\u0421\u0435\u043d\u043a\u0438\u201c, \u201e\u041f\u0440\u0435\u043a\u0443 \u0445\u043e\u0440\u0438\u0437\u043e\u043d\u0442\u043e\u0442\u201c, \u201e\u0418\u043d\u0441\u0430\u0458\u0434\u0435\u0440\u201c, \u201e\u0417\u043e\u043a\u0438 \u041f\u043e\u043a\u0438\u201c, \u201e\u041f\u0440\u043e\u0431\u043b\u0435\u043c\u043e\u0442 \u043d\u0430 \u0422\u0438\u043d\u0430\u201c, \u201e\u0417\u043c\u0438\u0458\u0430\u201c, \u201e\u041d\u0435\u043e\u043d\u0441\u043a\u0438 \u0441\u0440\u0446\u0430\u201c, \u201e\u041a\u043e\u043b\u0438\u0432\u043e\u201c, \u201e\u0421\u0438\u043d\u043e\u0442, \u0410\u043b\u0435\u0444 \u0438 \u0448\u0443\u043c\u0430\u0440\u043e\u0442\u201c (To guard a mountain, 2012 by Izer Aliu) \u043a\u043e\u0458 \u0434\u043e\u0431\u0438 \u043d\u0435\u043a\u043e\u043b\u043a\u0443 \u0441\u0432\u0435\u0442\u0441\u043a\u0438 \u043d\u0430\u0433\u0440\u0430\u0434\u0438 \u0438 \u0435 \u043d\u043e\u043c\u0438\u043d\u0438\u0440\u0430\u043d \u0437\u0430 \u0441\u0442\u0443\u0434\u0435\u043d\u0442\u0441\u043a\u0438 \u041e\u0441\u043a\u0430\u0440 \u0432\u043e 2013 \u0433\u043e\u0434\u0438\u043d\u0430.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0418\u043b\u0438\u043d\u0430 \u0410\u043d\u0433\u0435\u043b\u043e\u0432\u0441\u043a\u0430 \u0435 \u0434\u0438\u043f\u043b\u043e\u043c\u0438\u0440\u0430\u043d \u043b\u0438\u043a\u043e\u0432\u0435\u043d \u0443\u043c\u0435\u0442\u043d\u0438\u043a \u043d\u0430 \u0424\u0430\u043a\u0443\u043b\u0442\u0435\u0442\u043e\u0442 \u0437\u0430 \u043b\u0438\u043a\u043e\u0432\u043d\u0438 \u0443\u043c\u0435\u0442\u043d\u043e\u0441\u0442\u0438 \u0432\u043e \u0421\u043a\u043e\u043f\u0458\u0435. \u041f\u043e\u0432\u0435\u045c\u0435 \u043e\u0434 15 \u0433\u043e\u0434\u0438\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e \u0441\u0435 \u0437\u0430\u043d\u0438\u043c\u0430\u0432\u0430 \u0441\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430 \u0438 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430, \u0432\u043e \u0441\u0444\u0435\u0440\u0430\u0442\u0430 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u043e\u0442 \u0438 \u0444\u0438\u043b\u043c\u043e\u0442, \u0430 \u043e\u0434 \u0408\u0430\u043d\u0443\u0430\u0440\u0438 2013 \u0433\u043e\u0434\u0438\u043d\u0430 \u0435 \u0432\u0440\u0430\u0431\u043e\u0442\u0435\u043d\u0430 \u0432\u043e \u041c\u0430\u043a\u0435\u0434\u043e\u043d\u0441\u043a\u0438\u043e\u0442 \u041d\u0430\u0440\u043e\u0434\u0435\u043d \u0422\u0435\u0430\u0442\u0430\u0440, \u043a\u0430\u043a\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444. \u0418\u043b\u0438\u043d\u0430 \u0438\u043c\u0430 \u0440\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u0430\u043d\u043e \u043f\u0440\u0435\u043a\u0443 50 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0438, \u043c\u0435\u0453\u0443 \u043a\u043e\u0438 \u0438 20\u0442\u0438\u043d\u0430 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0438. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[40,41],"tags":[],"class_list":["post-4340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-matters-series","category-podcast"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tamara Ristoska invites Ilina Angelovska - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tamara Ristoska invites Ilina Angelovska - Europe House\" \/>\n<meta property=\"og:description\" content=\"\u0418\u043b\u0438\u043d\u0430 \u0410\u043d\u0433\u0435\u043b\u043e\u0432\u0441\u043a\u0430 \u0435 \u0434\u0438\u043f\u043b\u043e\u043c\u0438\u0440\u0430\u043d \u043b\u0438\u043a\u043e\u0432\u0435\u043d \u0443\u043c\u0435\u0442\u043d\u0438\u043a \u043d\u0430 \u0424\u0430\u043a\u0443\u043b\u0442\u0435\u0442\u043e\u0442 \u0437\u0430 \u043b\u0438\u043a\u043e\u0432\u043d\u0438 \u0443\u043c\u0435\u0442\u043d\u043e\u0441\u0442\u0438 \u0432\u043e \u0421\u043a\u043e\u043f\u0458\u0435. \u041f\u043e\u0432\u0435\u045c\u0435 \u043e\u0434 15 \u0433\u043e\u0434\u0438\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e \u0441\u0435 \u0437\u0430\u043d\u0438\u043c\u0430\u0432\u0430 \u0441\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430 \u0438 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430, \u0432\u043e \u0441\u0444\u0435\u0440\u0430\u0442\u0430 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u043e\u0442 \u0438 \u0444\u0438\u043b\u043c\u043e\u0442, \u0430 \u043e\u0434 \u0408\u0430\u043d\u0443\u0430\u0440\u0438 2013 \u0433\u043e\u0434\u0438\u043d\u0430 \u0435 \u0432\u0440\u0430\u0431\u043e\u0442\u0435\u043d\u0430 \u0432\u043e \u041c\u0430\u043a\u0435\u0434\u043e\u043d\u0441\u043a\u0438\u043e\u0442 \u041d\u0430\u0440\u043e\u0434\u0435\u043d \u0422\u0435\u0430\u0442\u0430\u0440, \u043a\u0430\u043a\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444. \u0418\u043b\u0438\u043d\u0430 \u0438\u043c\u0430 \u0440\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u0430\u043d\u043e \u043f\u0440\u0435\u043a\u0443 50 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0438, \u043c\u0435\u0453\u0443 \u043a\u043e\u0438 \u0438 20\u0442\u0438\u043d\u0430 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0438. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-03T11:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Tamara Ristoska invites Ilina Angelovska\",\"datePublished\":\"2021-12-03T11:57:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg\",\"articleSection\":[\"Culture Matters Series\",\"Podcast\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\",\"url\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\",\"name\":\"Tamara Ristoska invites Ilina Angelovska - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg\",\"datePublished\":\"2021-12-03T11:57:24+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg\",\"width\":800,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tamara Ristoska invites Ilina Angelovska - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/","og_locale":"en_US","og_type":"article","og_title":"Tamara Ristoska invites Ilina Angelovska - Europe House","og_description":"\u0418\u043b\u0438\u043d\u0430 \u0410\u043d\u0433\u0435\u043b\u043e\u0432\u0441\u043a\u0430 \u0435 \u0434\u0438\u043f\u043b\u043e\u043c\u0438\u0440\u0430\u043d \u043b\u0438\u043a\u043e\u0432\u0435\u043d \u0443\u043c\u0435\u0442\u043d\u0438\u043a \u043d\u0430 \u0424\u0430\u043a\u0443\u043b\u0442\u0435\u0442\u043e\u0442 \u0437\u0430 \u043b\u0438\u043a\u043e\u0432\u043d\u0438 \u0443\u043c\u0435\u0442\u043d\u043e\u0441\u0442\u0438 \u0432\u043e \u0421\u043a\u043e\u043f\u0458\u0435. \u041f\u043e\u0432\u0435\u045c\u0435 \u043e\u0434 15 \u0433\u043e\u0434\u0438\u043d\u0438 \u0430\u043a\u0442\u0438\u0432\u043d\u043e \u0441\u0435 \u0437\u0430\u043d\u0438\u043c\u0430\u0432\u0430 \u0441\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430 \u0438 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0458\u0430, \u0432\u043e \u0441\u0444\u0435\u0440\u0430\u0442\u0430 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u043e\u0442 \u0438 \u0444\u0438\u043b\u043c\u043e\u0442, \u0430 \u043e\u0434 \u0408\u0430\u043d\u0443\u0430\u0440\u0438 2013 \u0433\u043e\u0434\u0438\u043d\u0430 \u0435 \u0432\u0440\u0430\u0431\u043e\u0442\u0435\u043d\u0430 \u0432\u043e \u041c\u0430\u043a\u0435\u0434\u043e\u043d\u0441\u043a\u0438\u043e\u0442 \u041d\u0430\u0440\u043e\u0434\u0435\u043d \u0422\u0435\u0430\u0442\u0430\u0440, \u043a\u0430\u043a\u043e \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444. \u0418\u043b\u0438\u043d\u0430 \u0438\u043c\u0430 \u0440\u0435\u0430\u043b\u0438\u0437\u0438\u0440\u0430\u043d\u043e \u043f\u0440\u0435\u043a\u0443 50 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0441\u0446\u0435\u043d\u043e\u0433\u0440\u0430\u0444\u0438\u0438, \u043c\u0435\u0453\u0443 \u043a\u043e\u0438 \u0438 20\u0442\u0438\u043d\u0430 \u043a\u043e\u0441\u0442\u0438\u043c\u043e\u0433\u0440\u0430\u0444\u0438\u0438. [&hellip;]","og_url":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/","og_site_name":"Europe House","article_published_time":"2021-12-03T11:57:24+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#article","isPartOf":{"@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Tamara Ristoska invites Ilina Angelovska","datePublished":"2021-12-03T11:57:24+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg","articleSection":["Culture Matters Series","Podcast"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/","url":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/","name":"Tamara Ristoska invites Ilina Angelovska - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg","datePublished":"2021-12-03T11:57:24+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mksq\/tamara-ristoska-invites-ilina-angelovska\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/12\/261523486_4814221098639849_6894307169624024470_n.jpg","width":800,"height":800},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/4340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=4340"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/4340\/revisions"}],"predecessor-version":[{"id":4344,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/4340\/revisions\/4344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/4341"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=4340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=4340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=4340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}