{"id":429,"date":"2020-01-30T15:01:16","date_gmt":"2020-01-30T15:01:16","guid":{"rendered":"http:\/\/superhost.com.mk\/euhouse\/?p=429"},"modified":"2020-01-31T15:02:36","modified_gmt":"2020-01-31T15:02:36","slug":"creative-talks-2","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/creative-talks-2\/","title":{"rendered":"Creative Talks 2"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-429 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8728.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8728.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8728.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8728-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8728-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8731.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8731.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8731.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8731-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8731-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8777.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8777.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8777.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8777-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8777-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8734.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8734.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8734.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8734-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8734-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8771.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8771.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8771.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8771-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8771-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8763.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8763.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8763.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8763-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8763-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8765.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8765.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8765-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8765-768x512.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":434,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creative Talks 2 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkcreative-talks-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creative Talks 2 - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkcreative-talks-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-30T15:01:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-31T15:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Creative Talks 2\",\"datePublished\":\"2020-01-30T15:01:16+00:00\",\"dateModified\":\"2020-01-31T15:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkcreative-talks-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/\",\"url\":\"https:\/\/europehouse.mkcreative-talks-2\/\",\"name\":\"Creative Talks 2 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\",\"datePublished\":\"2020-01-30T15:01:16+00:00\",\"dateModified\":\"2020-01-31T15:02:36+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkcreative-talks-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creative Talks 2 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkcreative-talks-2\/","og_locale":"en_US","og_type":"article","og_title":"Creative Talks 2 - Europe House","og_url":"https:\/\/europehouse.mkcreative-talks-2\/","og_site_name":"Europe House","article_published_time":"2020-01-30T15:01:16+00:00","article_modified_time":"2020-01-31T15:02:36+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkcreative-talks-2\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkcreative-talks-2\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Creative Talks 2","datePublished":"2020-01-30T15:01:16+00:00","dateModified":"2020-01-31T15:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkcreative-talks-2\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkcreative-talks-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkcreative-talks-2\/","url":"https:\/\/europehouse.mkcreative-talks-2\/","name":"Creative Talks 2 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg","datePublished":"2020-01-30T15:01:16+00:00","dateModified":"2020-01-31T15:02:36+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkcreative-talks-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkcreative-talks-2\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/20200130-DSC_8740.jpg","width":1000,"height":667},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"predecessor-version":[{"id":439,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/429\/revisions\/439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/434"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}