{"id":3785,"date":"2021-10-06T11:28:18","date_gmt":"2021-10-06T11:28:18","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=3785"},"modified":"2021-10-12T11:31:44","modified_gmt":"2021-10-12T11:31:44","slug":"eco-photography-open-air-exhibition-strumica","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/eco-photography-open-air-exhibition-strumica\/","title":{"rendered":"Eco photography &#8211; Open air exhibition (Strumica)"},"content":{"rendered":"<p>As a culmination of the series of workshops &#8220;Basics of photography&#8221; under the mentorship of Stole Angelov and &#8220;Eco Photography&#8221; under the mentorship of Aleksandar Donchev, which were held last month organized by Europe House Strumica, our young heroes opened Eco photography &#8211; Open air exhibition.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3786\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/1-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3789\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/2-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/2-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/2-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/2-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/2-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3795\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/4-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/4-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/4-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/4-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/4-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3798\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/5-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/5-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/5-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/5-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/5-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3801\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/6-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/6-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/6-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/6-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/6-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3804\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/7-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/7-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/7-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/7-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/7-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3807\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/8-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/8-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/8-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/8-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/8-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3810\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/9-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/9-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/9-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/9-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/9-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3813\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/10-1-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/10-1-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/10-1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/10-1-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/10-1.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3816\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/11-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/11-1024x684.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/11-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/11-768x513.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/11.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As a culmination of the series of workshops &#8220;Basics of photography&#8221; under the mentorship of Stole Angelov and &#8220;Eco Photography&#8221; under the mentorship of Aleksandar Donchev, which were held last month organized by Europe House Strumica, our young heroes opened Eco photography &#8211; Open air exhibition. &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":3786,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eco photography - Open air exhibition (Strumica) - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eco photography - Open air exhibition (Strumica) - Europe House\" \/>\n<meta property=\"og:description\" content=\"As a culmination of the series of workshops &#8220;Basics of photography&#8221; under the mentorship of Stole Angelov and &#8220;Eco Photography&#8221; under the mentorship of Aleksandar Donchev, which were held last month organized by Europe House Strumica, our young heroes opened Eco photography &#8211; Open air exhibition. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T11:28:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-12T11:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1002\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"Eco photography &#8211; Open air exhibition (Strumica)\",\"datePublished\":\"2021-10-06T11:28:18+00:00\",\"dateModified\":\"2021-10-12T11:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\"},\"wordCount\":54,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\",\"url\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\",\"name\":\"Eco photography - Open air exhibition (Strumica) - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg\",\"datePublished\":\"2021-10-06T11:28:18+00:00\",\"dateModified\":\"2021-10-12T11:31:44+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg\",\"width\":1500,\"height\":1002},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eco photography - Open air exhibition (Strumica) - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/","og_locale":"en_US","og_type":"article","og_title":"Eco photography - Open air exhibition (Strumica) - Europe House","og_description":"As a culmination of the series of workshops &#8220;Basics of photography&#8221; under the mentorship of Stole Angelov and &#8220;Eco Photography&#8221; under the mentorship of Aleksandar Donchev, which were held last month organized by Europe House Strumica, our young heroes opened Eco photography &#8211; Open air exhibition. &nbsp;","og_url":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/","og_site_name":"Europe House","article_published_time":"2021-10-06T11:28:18+00:00","article_modified_time":"2021-10-12T11:31:44+00:00","og_image":[{"width":1500,"height":1002,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/10\/1-1.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"Eco photography &#8211; Open air exhibition (Strumica)","datePublished":"2021-10-06T11:28:18+00:00","dateModified":"2021-10-12T11:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/"},"wordCount":54,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/","url":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/","name":"Eco photography - Open air exhibition (Strumica) - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg","datePublished":"2021-10-06T11:28:18+00:00","dateModified":"2021-10-12T11:31:44+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkeco-photography-open-air-exhibition-strumica\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/10\/1-1.jpg","width":1500,"height":1002},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=3785"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3785\/revisions"}],"predecessor-version":[{"id":3822,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3785\/revisions\/3822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/3786"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=3785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=3785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=3785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}