{"id":3493,"date":"2021-09-13T14:49:50","date_gmt":"2021-09-13T14:49:50","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=3493"},"modified":"2021-09-22T07:32:01","modified_gmt":"2021-09-22T07:32:01","slug":"connectingeuropeexpress","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/connectingeuropeexpress\/","title":{"rendered":"#ConnectingEuropeExpress"},"content":{"rendered":"<p>The &#8220;European train&#8221; arrived at the railway station in Skopje last night. From <span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t81\/1.5\/16\/1f1f5_1f1f9.png\" alt=\"\ud83c\uddf5\ud83c\uddf9\" width=\"16\" height=\"16\" \/><\/span>Lisbon to Paris through <span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb2\/1.5\/16\/32_20e3.png\" alt=\"2\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t2e\/1.5\/16\/36_20e3.png\" alt=\"6\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span> countries. #ConnectingEuropeExpress welcome to <span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb5\/1.5\/16\/1f1f2_1f1f0.png\" alt=\"\ud83c\uddf2\ud83c\uddf0\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td7\/1.5\/16\/2757.png\" alt=\"\u2757\ufe0f\" width=\"16\" height=\"16\" \/><\/span> Connecting Europe Express marks <span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb2\/1.5\/16\/32_20e3.png\" alt=\"2\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t74\/1.5\/16\/30_20e3.png\" alt=\"0\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb2\/1.5\/16\/32_20e3.png\" alt=\"2\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t93\/1.5\/16\/31_20e3.png\" alt=\"1\ufe0f\u20e3\" width=\"16\" height=\"16\" \/><\/span> as European Railway Year and promotes rail transport as a sustainable, safe and innovative <span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t27\/1.5\/16\/1f688.png\" alt=\"\ud83d\ude88\" width=\"16\" height=\"16\" \/><\/span><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t16\/1.5\/16\/1f6e4.png\" alt=\"\ud83d\udee4\" width=\"16\" height=\"16\" \/><\/span>. #EuropeanYearofRail #ConnectingEuropeExpress #EUGreenDeal<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3494\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1-1024x683.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1-768x512.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1-1536x1024.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg 1620w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3497\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/2-1024x681.jpg\" alt=\"\" width=\"1024\" height=\"681\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/2-1024x681.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/2-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/2-768x511.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/2-1536x1022.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/2.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3500\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/3-1024x681.jpg\" alt=\"\" width=\"1024\" height=\"681\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/3-1024x681.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/3-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/3-768x511.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/3-1536x1022.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/3.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3509\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/6-1024x681.jpg\" alt=\"\" width=\"1024\" height=\"681\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/6-1024x681.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/6-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/6-768x511.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/6-1536x1022.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/6.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3512\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/7-1024x681.jpg\" alt=\"\" width=\"1024\" height=\"681\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/7-1024x681.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/7-300x200.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/7-768x511.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/7-1536x1022.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/7.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The &#8220;European train&#8221; arrived at the railway station in Skopje last night. From Lisbon to Paris through countries. #ConnectingEuropeExpress welcome to Connecting Europe Express marks as European Railway Year and promotes rail transport as a sustainable, safe and innovative . #EuropeanYearofRail #ConnectingEuropeExpress #EUGreenDeal &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":3494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#ConnectingEuropeExpress - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkconnectingeuropeexpress\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#ConnectingEuropeExpress - Europe House\" \/>\n<meta property=\"og:description\" content=\"The &#8220;European train&#8221; arrived at the railway station in Skopje last night. From Lisbon to Paris through countries. #ConnectingEuropeExpress welcome to Connecting Europe Express marks as European Railway Year and promotes rail transport as a sustainable, safe and innovative . #EuropeanYearofRail #ConnectingEuropeExpress #EUGreenDeal &nbsp; &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkconnectingeuropeexpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-13T14:49:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T07:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"#ConnectingEuropeExpress\",\"datePublished\":\"2021-09-13T14:49:50+00:00\",\"dateModified\":\"2021-09-22T07:32:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/\"},\"wordCount\":46,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkconnectingeuropeexpress\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/\",\"url\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/\",\"name\":\"#ConnectingEuropeExpress - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg\",\"datePublished\":\"2021-09-13T14:49:50+00:00\",\"dateModified\":\"2021-09-22T07:32:01+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkconnectingeuropeexpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#ConnectingEuropeExpress - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkconnectingeuropeexpress\/","og_locale":"en_US","og_type":"article","og_title":"#ConnectingEuropeExpress - Europe House","og_description":"The &#8220;European train&#8221; arrived at the railway station in Skopje last night. From Lisbon to Paris through countries. #ConnectingEuropeExpress welcome to Connecting Europe Express marks as European Railway Year and promotes rail transport as a sustainable, safe and innovative . #EuropeanYearofRail #ConnectingEuropeExpress #EUGreenDeal &nbsp; &nbsp; &nbsp;","og_url":"https:\/\/europehouse.mkconnectingeuropeexpress\/","og_site_name":"Europe House","article_published_time":"2021-09-13T14:49:50+00:00","article_modified_time":"2021-09-22T07:32:01+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/09\/1.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"#ConnectingEuropeExpress","datePublished":"2021-09-13T14:49:50+00:00","dateModified":"2021-09-22T07:32:01+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/"},"wordCount":46,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkconnectingeuropeexpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/","url":"https:\/\/europehouse.mkconnectingeuropeexpress\/","name":"#ConnectingEuropeExpress - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg","datePublished":"2021-09-13T14:49:50+00:00","dateModified":"2021-09-22T07:32:01+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkconnectingeuropeexpress\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkconnectingeuropeexpress\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/09\/1.jpg","width":1620,"height":1080},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=3493"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3493\/revisions"}],"predecessor-version":[{"id":3515,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3493\/revisions\/3515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/3494"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=3493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=3493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=3493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}