{"id":3388,"date":"2021-08-29T22:28:39","date_gmt":"2021-08-29T22:28:39","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=3388"},"modified":"2021-08-29T22:28:39","modified_gmt":"2021-08-29T22:28:39","slug":"knizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/knizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/","title":{"rendered":"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/kQ_HGznwOWc?start=1&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3389,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[40,41],"tags":[],"class_list":["post-3388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-matters-series","category-podcast"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-\u0453oko-zdraveski\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-\u0453oko-zdraveski\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-29T22:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/08\/citacot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2526\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438\",\"datePublished\":\"2021-08-29T22:28:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/\"},\"wordCount\":20,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg\",\"articleSection\":[\"Culture Matters Series\",\"Podcast\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/\",\"url\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/\",\"name\":\"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg\",\"datePublished\":\"2021-08-29T22:28:39+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg\",\"width\":2526,\"height\":1425},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-\u0453oko-zdraveski\/","og_locale":"en_US","og_type":"article","og_title":"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House","og_url":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-\u0453oko-zdraveski\/","og_site_name":"Europe House","article_published_time":"2021-08-29T22:28:39+00:00","og_image":[{"width":2526,"height":1425,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/08\/citacot.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438","datePublished":"2021-08-29T22:28:39+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/"},"wordCount":20,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg","articleSection":["Culture Matters Series","Podcast"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/","url":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/","name":"\u041a\u043d\u0438\u0436\u0435\u0432\u043d\u0438 \u0440\u0435\u0446\u0435\u043d\u0437\u0438\u0438 \u0438 \u0440\u0430\u0437\u0433\u043e\u0432\u043e\u0440\u0438 \u0441\u043e \u0427\u0438\u0442\u0430\u0447\u043e\u0442. \u0413\u043e\u0441\u0442\u0438\u043d: \u0403\u043e\u043a\u043e \u0417\u0434\u0440\u0430\u0432\u0435\u0441\u043a\u0438 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg","datePublished":"2021-08-29T22:28:39+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkknizhevni-reczenzii-i-razgovori-so-chitachot-gostin-%d1%93oko-zdraveski\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/citacot.jpg","width":2526,"height":1425},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=3388"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3388\/revisions"}],"predecessor-version":[{"id":3392,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3388\/revisions\/3392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/3389"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=3388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=3388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=3388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}