{"id":3352,"date":"2021-08-06T10:56:57","date_gmt":"2021-08-06T10:56:57","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=3352"},"modified":"2021-08-17T10:58:59","modified_gmt":"2021-08-17T10:58:59","slug":"youth-talks-in-strumica","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/youth-talks-in-strumica\/","title":{"rendered":"#Youth Talks in Strumica"},"content":{"rendered":"<p>\ud83d\uddef #YouthTalks continued in Strumica!<br \/>\nAmbassador David Geer openly discussed with young people about everyday challenges, environmental protection, raising awareness of the inclusion of disabilities, the fight against stereotypes.<\/p>\n<div id='gallery-1' class='gallery galleryid-3352 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05480-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05503-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05448-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05473-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05443-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05467-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05434-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05462-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458-538x538.jpg 538w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\uddef #YouthTalks continued in Strumica! Ambassador David Geer openly discussed with young people about everyday challenges, environmental protection, raising awareness of the inclusion of disabilities, the fight against stereotypes.<\/p>\n","protected":false},"author":2,"featured_media":3334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#Youth Talks in Strumica - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Youth Talks in Strumica - Europe House\" \/>\n<meta property=\"og:description\" content=\"\ud83d\uddef #YouthTalks continued in Strumica! Ambassador David Geer openly discussed with young people about everyday challenges, environmental protection, raising awareness of the inclusion of disabilities, the fight against stereotypes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-06T10:56:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-17T10:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/08\/dsc05458.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"#Youth Talks in Strumica\",\"datePublished\":\"2021-08-06T10:56:57+00:00\",\"dateModified\":\"2021-08-17T10:58:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\"},\"wordCount\":34,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\",\"url\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\",\"name\":\"#Youth Talks in Strumica - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg\",\"datePublished\":\"2021-08-06T10:56:57+00:00\",\"dateModified\":\"2021-08-17T10:58:59+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkyouth-talks-in-strumica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg\",\"width\":1616,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#Youth Talks in Strumica - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkyouth-talks-in-strumica\/","og_locale":"en_US","og_type":"article","og_title":"#Youth Talks in Strumica - Europe House","og_description":"\ud83d\uddef #YouthTalks continued in Strumica! Ambassador David Geer openly discussed with young people about everyday challenges, environmental protection, raising awareness of the inclusion of disabilities, the fight against stereotypes.","og_url":"https:\/\/europehouse.mkyouth-talks-in-strumica\/","og_site_name":"Europe House","article_published_time":"2021-08-06T10:56:57+00:00","article_modified_time":"2021-08-17T10:58:59+00:00","og_image":[{"width":1616,"height":1080,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/08\/dsc05458.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"#Youth Talks in Strumica","datePublished":"2021-08-06T10:56:57+00:00","dateModified":"2021-08-17T10:58:59+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/"},"wordCount":34,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkyouth-talks-in-strumica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/","url":"https:\/\/europehouse.mkyouth-talks-in-strumica\/","name":"#Youth Talks in Strumica - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg","datePublished":"2021-08-06T10:56:57+00:00","dateModified":"2021-08-17T10:58:59+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkyouth-talks-in-strumica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkyouth-talks-in-strumica\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/08\/dsc05458.jpg","width":1616,"height":1080},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=3352"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3352\/revisions"}],"predecessor-version":[{"id":3353,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/3352\/revisions\/3353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/3334"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=3352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=3352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=3352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}