{"id":2522,"date":"2021-05-20T21:19:49","date_gmt":"2021-05-20T21:19:49","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=2522"},"modified":"2021-06-14T18:59:46","modified_gmt":"2021-06-14T18:59:46","slug":"the-basics-of-the-dramatic-text","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/the-basics-of-the-dramatic-text\/","title":{"rendered":"The basics of the dramatic text"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2523\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/1-6-1024x671.jpeg\" alt=\"\" width=\"1024\" height=\"671\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6-1024x671.jpeg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6-300x197.jpeg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6-768x503.jpeg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg 1520w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2526\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/2-6-1024x667.jpeg\" alt=\"\" width=\"1024\" height=\"667\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/2-6-1024x667.jpeg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/2-6-300x195.jpeg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/2-6-768x500.jpeg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/2-6.jpeg 1518w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2529\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/3-5-1024x628.jpeg\" alt=\"\" width=\"1024\" height=\"628\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/3-5-1024x628.jpeg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/3-5-300x184.jpeg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/3-5-768x471.jpeg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/3-5.jpeg 1514w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2532\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/4-1024x664.png\" alt=\"\" width=\"1024\" height=\"664\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/4-1024x664.png 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/4-300x194.png 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/4-768x498.png 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/4.png 1518w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2535\" src=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/5-5-1024x675.jpeg\" alt=\"\" width=\"1024\" height=\"675\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/5-5-1024x675.jpeg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/5-5-300x198.jpeg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/5-5-768x507.jpeg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/5-5.jpeg 1519w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2523,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The basics of the dramatic text - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The basics of the dramatic text - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T21:19:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-14T18:59:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/1-6.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1520\" \/>\n\t<meta property=\"og:image:height\" content=\"996\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"The basics of the dramatic text\",\"datePublished\":\"2021-05-20T21:19:49+00:00\",\"dateModified\":\"2021-06-14T18:59:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\",\"url\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\",\"name\":\"The basics of the dramatic text - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg\",\"datePublished\":\"2021-05-20T21:19:49+00:00\",\"dateModified\":\"2021-06-14T18:59:46+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg\",\"width\":1520,\"height\":996},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The basics of the dramatic text - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/","og_locale":"en_US","og_type":"article","og_title":"The basics of the dramatic text - Europe House","og_url":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/","og_site_name":"Europe House","article_published_time":"2021-05-20T21:19:49+00:00","article_modified_time":"2021-06-14T18:59:46+00:00","og_image":[{"width":1520,"height":996,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/05\/1-6.jpeg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"The basics of the dramatic text","datePublished":"2021-05-20T21:19:49+00:00","dateModified":"2021-06-14T18:59:46+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/","url":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/","name":"The basics of the dramatic text - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg","datePublished":"2021-05-20T21:19:49+00:00","dateModified":"2021-06-14T18:59:46+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkthe-basics-of-the-dramatic-text\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/05\/1-6.jpeg","width":1520,"height":996},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/2522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=2522"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/2522\/revisions"}],"predecessor-version":[{"id":2538,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/2522\/revisions\/2538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/2523"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=2522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=2522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=2522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}