{"id":1728,"date":"2020-11-20T14:57:00","date_gmt":"2020-11-20T14:57:00","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=1728"},"modified":"2020-12-04T14:58:30","modified_gmt":"2020-12-04T14:58:30","slug":"world-childrens-day-2","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/world-childrens-day-2\/","title":{"rendered":"World Children&#8217;s Day"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-1728 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-300x203.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1024x693.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-768x520.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1536x1040.jpg 1536w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2048x1387.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2-200x300.jpg 200w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2-683x1024.jpg 683w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2-768x1152.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2-1024x1536.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-2.jpg 1280w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-300x300.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-1024x1024.jpg 1024w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-150x150.jpg 150w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-768x768.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-250x250.jpg 250w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1-350x350.jpg 350w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-1.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>World Children&#039;s Day - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkworld-childrens-day-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"World Children&#039;s Day - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkworld-childrens-day-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-20T14:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-04T14:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"World Children&#8217;s Day\",\"datePublished\":\"2020-11-20T14:57:00+00:00\",\"dateModified\":\"2020-12-04T14:58:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg\",\"articleSection\":[\"Media Gallery\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mkworld-childrens-day-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/\",\"url\":\"https:\/\/europehouse.mkworld-childrens-day-2\/\",\"name\":\"World Children's Day - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg\",\"datePublished\":\"2020-11-20T14:57:00+00:00\",\"dateModified\":\"2020-12-04T14:58:30+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkworld-childrens-day-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg\",\"width\":2560,\"height\":1733},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"World Children's Day - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkworld-childrens-day-2\/","og_locale":"en_US","og_type":"article","og_title":"World Children's Day - Europe House","og_url":"https:\/\/europehouse.mkworld-childrens-day-2\/","og_site_name":"Europe House","article_published_time":"2020-11-20T14:57:00+00:00","article_modified_time":"2020-12-04T14:58:30+00:00","og_image":[{"width":2560,"height":1733,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mkworld-childrens-day-2\/#article","isPartOf":{"@id":"https:\/\/europehouse.mkworld-childrens-day-2\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"World Children&#8217;s Day","datePublished":"2020-11-20T14:57:00+00:00","dateModified":"2020-12-04T14:58:30+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mkworld-childrens-day-2\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg","articleSection":["Media Gallery"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mkworld-childrens-day-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mkworld-childrens-day-2\/","url":"https:\/\/europehouse.mkworld-childrens-day-2\/","name":"World Children's Day - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg","datePublished":"2020-11-20T14:57:00+00:00","dateModified":"2020-12-04T14:58:30+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkworld-childrens-day-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkworld-childrens-day-2\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/12\/eu-blue-scaled.jpg","width":2560,"height":1733},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/1728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=1728"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/1728\/revisions"}],"predecessor-version":[{"id":1729,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/1728\/revisions\/1729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/1711"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=1728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=1728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=1728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}