{"id":131,"date":"2020-01-20T14:40:23","date_gmt":"2020-01-20T14:40:23","guid":{"rendered":"http:\/\/superhost.com.mk\/euhouse\/?p=131"},"modified":"2020-01-21T09:10:19","modified_gmt":"2020-01-21T09:10:19","slug":"%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019","status":"publish","type":"post","link":"https:\/\/europehouse.mk\/en\/%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/","title":{"rendered":"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/46Pn5DxWgmM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":140,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campaigns"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\u0441\u0440\u0435\u0434\u0431\u0430-\u0441\u043e-\u0441\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438-\u0432\u043e-europe-house-27-11-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\u0441\u0440\u0435\u0434\u0431\u0430-\u0441\u043e-\u0441\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438-\u0432\u043e-europe-house-27-11-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T14:40:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-21T09:10:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"milan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"milan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/\"},\"author\":{\"name\":\"milan\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\"},\"headline\":\"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019\",\"datePublished\":\"2020-01-20T14:40:23+00:00\",\"dateModified\":\"2020-01-21T09:10:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/\"},\"wordCount\":14,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg\",\"articleSection\":[\"Activities\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/\",\"url\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/\",\"name\":\"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg\",\"datePublished\":\"2020-01-20T14:40:23+00:00\",\"dateModified\":\"2020-01-21T09:10:19+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg\",\"width\":350,\"height\":186},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c\",\"name\":\"milan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g\",\"caption\":\"milan\"},\"url\":\"https:\/\/europehouse.mk\/en\/author\/milan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\u0441\u0440\u0435\u0434\u0431\u0430-\u0441\u043e-\u0441\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438-\u0432\u043e-europe-house-27-11-2019\/","og_locale":"en_US","og_type":"article","og_title":"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House","og_url":"https:\/\/europehouse.mk\u0441\u0440\u0435\u0434\u0431\u0430-\u0441\u043e-\u0441\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438-\u0432\u043e-europe-house-27-11-2019\/","og_site_name":"Europe House","article_published_time":"2020-01-20T14:40:23+00:00","article_modified_time":"2020-01-21T09:10:19+00:00","og_image":[{"width":350,"height":186,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg","type":"image\/jpeg"}],"author":"milan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"milan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#article","isPartOf":{"@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/"},"author":{"name":"milan","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c"},"headline":"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019","datePublished":"2020-01-20T14:40:23+00:00","dateModified":"2020-01-21T09:10:19+00:00","mainEntityOfPage":{"@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/"},"wordCount":14,"commentCount":0,"publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"image":{"@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg","articleSection":["Activities"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/","url":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/","name":"\u0421\u0440\u0435\u0434\u0431\u0430 \u0441\u043e \u0421\u0440\u0435\u0434\u043d\u043e\u0448\u043a\u043e\u043b\u0446\u0438 \u0432\u043e \u201eEurope House\u201c 27.11.2019 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg","datePublished":"2020-01-20T14:40:23+00:00","dateModified":"2020-01-21T09:10:19+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk%d1%81%d1%80%d0%b5%d0%b4%d0%b1%d0%b0-%d1%81%d0%be-%d1%81%d1%80%d0%b5%d0%b4%d0%bd%d0%be%d1%88%d0%ba%d0%be%d0%bb%d1%86%d0%b8-%d0%b2%d0%be-europe-house-27-11-2019\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/sredba-srednoskolci.jpg","width":350,"height":186},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europehouse.mk\/#\/schema\/person\/aa6e2d6a08fe131701ee5067911abb2c","name":"milan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/299db3b4b6f94903d3037b4ff9f36c339328bf67f6a94cd5d3e3fd1ed74f6480?s=96&d=mm&r=g","caption":"milan"},"url":"https:\/\/europehouse.mk\/en\/author\/milan\/"}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"predecessor-version":[{"id":132,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/posts\/131\/revisions\/132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/140"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}