{"id":6046,"date":"2021-07-12T09:40:46","date_gmt":"2021-07-12T09:40:46","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=3178"},"modified":"2021-07-12T09:40:46","modified_gmt":"2021-07-12T09:40:46","slug":"6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski","status":"publish","type":"podcast","link":"https:\/\/europehouse.mk\/en\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/","title":{"rendered":"#6 Tamara Ristoska invites Katerina Stefanovska &#038; Krume Stefanovski"},"content":{"rendered":"<div dir=\"auto\"><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5a\/1.5\/16\/1f3a7.png\" alt=\"\ud83c\udfa7\" width=\"16\" height=\"16\" \/><\/span>\u0412\u043e #6 \u043f\u043e\u0434\u043a\u0430\u0441\u0442 \u0441\u043e \u0422\u0430\u043c\u0430\u0440\u0430 \u0420\u0438\u0441\u0442\u043e\u0441\u043a\u0430 \u0437\u0431\u043e\u0440\u0443\u0432\u0430\u043c\u0435 \u0437\u0430 \u0441\u043b\u043e\u0431\u043e\u0434\u043d\u0438 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0444\u043e\u0440\u043c\u0438 \u043d\u0430 \u0438\u0437\u0440\u0430\u0437\u0443\u0432\u0430\u045a\u0435, \u0436\u0435\u043b\u0431\u0430\u0442\u0430 \u0437\u0430 \u043f\u043e\u0440\u0430\u0437\u0432\u0438\u0435\u043d\u043e \u043e\u043f\u0448\u0442\u0435\u0441\u0442\u0432\u043e \u0437\u0430 \u043c\u043b\u0430\u0434\u0430\u0442\u0430 \u043f\u043e\u043f\u0443\u043b\u0430\u0446\u0438\u0458\u0430 \u0438 \u0435\u0434\u0443\u043a\u0430\u0446\u0438\u0458\u0430 \u0438 \u043f\u043e\u0442\u0442\u0438\u043a\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0438\u043d\u043e\u0432\u0430\u0442\u0438\u0432\u043d\u0438\u0442\u0435 \u043c\u0435\u0442\u043e\u0434\u0438.<\/div>\n<div dir=\"auto\"><span class=\"pq6dq46d tbxw36s4 knj5qynh kvgmc6g5 ditlmg2l oygrvhab nvdbi5me sf5mxxl7 gl3lb2sf hhz5lgdu\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t84\/1.5\/16\/1f399.png\" alt=\"\ud83c\udf99\" width=\"16\" height=\"16\" \/><\/span>\u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0430 \u0440\u0430\u0431\u043e\u0442\u0438 \u0432\u043e \u043e\u0431\u043b\u0430\u0441\u0442\u0430 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u0430\u0442\u0430 \u043a\u0430\u043a\u043e \u043a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0442\u043e\u0440 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u043d\u0438 \u043d\u0430\u0441\u0442\u0430\u043d\u0438, \u0430 \u041a\u0440\u0443\u043c\u0435 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0438 \u0435 \u0430\u043a\u0442\u0435\u0440 \u0438 \u043c\u0443\u0437\u0438\u0447\u0430\u0440, \u043e\u0441\u043d\u043e\u0432\u0430\u0447 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0430\u0442\u0430 \u0433\u0440\u0443\u043f\u0430 \u0437\u0430 \u0441\u0435\u043d\u043a\u0438 \u0438 \u043e\u0431\u043b\u0438\u0446\u0438. \u0414\u0432\u0430\u0458\u0446\u0430\u0442\u0430 \u0441\u0435\u043a\u043e\u0433\u0430\u0448 \u0441\u0435 \u0432\u043e \u043f\u043e\u0442\u0440\u0430\u0433\u0430 \u043f\u043e \u043d\u043e\u0432 \u0438 \u0441\u0432\u0435\u0436 \u0438\u0437\u0440\u0430\u0437 \u0438 \u0437\u0430\u0442\u043e\u0430 \u0441\u0435 \u043e\u0434\u043b\u0438\u0447\u043d\u0438 \u0433\u043e\u0432\u043e\u0440\u043d\u0438\u0446\u0438 \u043d\u0430 \u043e\u0432\u0430\u0430 \u0442\u0435\u043c\u0430.<\/div>\n<div dir=\"auto\"><iframe loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/3P2In3fWVOpWDYVRotijLe\" width=\"100%\" height=\"232\" frameborder=\"0\"><\/iframe><\/div>\n","protected":false},"featured_media":3179,"template":"","class_list":["post-6046","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#6 Tamara Ristoska invites Katerina Stefanovska &amp; Krume Stefanovski - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#6 Tamara Ristoska invites Katerina Stefanovska &amp; Krume Stefanovski - Europe House\" \/>\n<meta property=\"og:description\" content=\"\u0412\u043e #6 \u043f\u043e\u0434\u043a\u0430\u0441\u0442 \u0441\u043e \u0422\u0430\u043c\u0430\u0440\u0430 \u0420\u0438\u0441\u0442\u043e\u0441\u043a\u0430 \u0437\u0431\u043e\u0440\u0443\u0432\u0430\u043c\u0435 \u0437\u0430 \u0441\u043b\u043e\u0431\u043e\u0434\u043d\u0438 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0444\u043e\u0440\u043c\u0438 \u043d\u0430 \u0438\u0437\u0440\u0430\u0437\u0443\u0432\u0430\u045a\u0435, \u0436\u0435\u043b\u0431\u0430\u0442\u0430 \u0437\u0430 \u043f\u043e\u0440\u0430\u0437\u0432\u0438\u0435\u043d\u043e \u043e\u043f\u0448\u0442\u0435\u0441\u0442\u0432\u043e \u0437\u0430 \u043c\u043b\u0430\u0434\u0430\u0442\u0430 \u043f\u043e\u043f\u0443\u043b\u0430\u0446\u0438\u0458\u0430 \u0438 \u0435\u0434\u0443\u043a\u0430\u0446\u0438\u0458\u0430 \u0438 \u043f\u043e\u0442\u0442\u0438\u043a\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0438\u043d\u043e\u0432\u0430\u0442\u0438\u0432\u043d\u0438\u0442\u0435 \u043c\u0435\u0442\u043e\u0434\u0438. \u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0430 \u0440\u0430\u0431\u043e\u0442\u0438 \u0432\u043e \u043e\u0431\u043b\u0430\u0441\u0442\u0430 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u0430\u0442\u0430 \u043a\u0430\u043a\u043e \u043a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0442\u043e\u0440 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u043d\u0438 \u043d\u0430\u0441\u0442\u0430\u043d\u0438, \u0430 \u041a\u0440\u0443\u043c\u0435 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0438 \u0435 \u0430\u043a\u0442\u0435\u0440 \u0438 \u043c\u0443\u0437\u0438\u0447\u0430\u0440, \u043e\u0441\u043d\u043e\u0432\u0430\u0447 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0430\u0442\u0430 \u0433\u0440\u0443\u043f\u0430 \u0437\u0430 \u0441\u0435\u043d\u043a\u0438 \u0438 \u043e\u0431\u043b\u0438\u0446\u0438. \u0414\u0432\u0430\u0458\u0446\u0430\u0442\u0430 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/\",\"url\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/\",\"name\":\"#6 Tamara Ristoska invites Katerina Stefanovska & Krume Stefanovski - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg\",\"datePublished\":\"2021-07-12T09:40:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Podcasts\",\"item\":\"https:\/\/europehouse.mkmk\/podcast\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#6 Tamara Ristoska invites Katerina Stefanovska &#038; Krume Stefanovski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#6 Tamara Ristoska invites Katerina Stefanovska & Krume Stefanovski - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/","og_locale":"en_US","og_type":"article","og_title":"#6 Tamara Ristoska invites Katerina Stefanovska & Krume Stefanovski - Europe House","og_description":"\u0412\u043e #6 \u043f\u043e\u0434\u043a\u0430\u0441\u0442 \u0441\u043e \u0422\u0430\u043c\u0430\u0440\u0430 \u0420\u0438\u0441\u0442\u043e\u0441\u043a\u0430 \u0437\u0431\u043e\u0440\u0443\u0432\u0430\u043c\u0435 \u0437\u0430 \u0441\u043b\u043e\u0431\u043e\u0434\u043d\u0438 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0438 \u0444\u043e\u0440\u043c\u0438 \u043d\u0430 \u0438\u0437\u0440\u0430\u0437\u0443\u0432\u0430\u045a\u0435, \u0436\u0435\u043b\u0431\u0430\u0442\u0430 \u0437\u0430 \u043f\u043e\u0440\u0430\u0437\u0432\u0438\u0435\u043d\u043e \u043e\u043f\u0448\u0442\u0435\u0441\u0442\u0432\u043e \u0437\u0430 \u043c\u043b\u0430\u0434\u0430\u0442\u0430 \u043f\u043e\u043f\u0443\u043b\u0430\u0446\u0438\u0458\u0430 \u0438 \u0435\u0434\u0443\u043a\u0430\u0446\u0438\u0458\u0430 \u0438 \u043f\u043e\u0442\u0442\u0438\u043a\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0438\u043d\u043e\u0432\u0430\u0442\u0438\u0432\u043d\u0438\u0442\u0435 \u043c\u0435\u0442\u043e\u0434\u0438. \u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0430 \u0440\u0430\u0431\u043e\u0442\u0438 \u0432\u043e \u043e\u0431\u043b\u0430\u0441\u0442\u0430 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u0430\u0442\u0430 \u043a\u0430\u043a\u043e \u043a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0442\u043e\u0440 \u043d\u0430 \u043a\u0443\u043b\u0442\u0443\u0440\u043d\u0438 \u043d\u0430\u0441\u0442\u0430\u043d\u0438, \u0430 \u041a\u0440\u0443\u043c\u0435 \u0421\u0442\u0435\u0444\u0430\u043d\u043e\u0432\u0441\u043a\u0438 \u0435 \u0430\u043a\u0442\u0435\u0440 \u0438 \u043c\u0443\u0437\u0438\u0447\u0430\u0440, \u043e\u0441\u043d\u043e\u0432\u0430\u0447 \u043d\u0430 \u0442\u0435\u0430\u0442\u0430\u0440\u0441\u043a\u0430\u0442\u0430 \u0433\u0440\u0443\u043f\u0430 \u0437\u0430 \u0441\u0435\u043d\u043a\u0438 \u0438 \u043e\u0431\u043b\u0438\u0446\u0438. \u0414\u0432\u0430\u0458\u0446\u0430\u0442\u0430 [&hellip;]","og_url":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/","og_site_name":"Europe House","og_image":[{"width":2048,"height":2048,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/","url":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/","name":"#6 Tamara Ristoska invites Katerina Stefanovska & Krume Stefanovski - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg","datePublished":"2021-07-12T09:40:46+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/07\/217844613_4375152649213365_4669749400069212573_n.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mkmk\/podcast\/6-tamara-ristoska-invites-katerina-stefanovska-krume-stefanovski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Podcasts","item":"https:\/\/europehouse.mkmk\/podcast\/"},{"@type":"ListItem","position":2,"name":"#6 Tamara Ristoska invites Katerina Stefanovska &#038; Krume Stefanovski"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/podcast\/6046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/podcast"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/3179"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=6046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}