{"id":21853,"date":"2023-02-27T15:02:46","date_gmt":"2023-02-27T15:02:46","guid":{"rendered":"https:\/\/euhouse.mk\/?post_type=podcast&#038;p=21853"},"modified":"2023-02-28T15:05:34","modified_gmt":"2023-02-28T15:05:34","slug":"40-tamara-risteska-invites-bloom","status":"publish","type":"podcast","link":"https:\/\/europehouse.mk\/en\/podcast\/40-tamara-risteska-invites-bloom\/","title":{"rendered":"#40 Tamara Ristoska invites Bloom"},"content":{"rendered":"<p>\u0410\u043d\u0434\u0440\u0438\u0458\u0430\u043d\u0430 \u0438 \u0411\u0438\u0441\u0435\u0440\u0430 \u0441\u0435 \u0434\u0435\u0432\u043e\u0458\u043a\u0438\u0442\u0435 \u043a\u043e\u0438 \u043e\u0434 \u0438\u0434\u0435\u0458\u0430 \u0441\u043e\u0437\u0434\u0430\u0434\u043e\u0430 \u043f\u0440\u0438\u043a\u0430\u0437\u043d\u0430 \u043a\u043e\u0458\u0430 \u0432\u043b\u0438\u0458\u0430\u0435 \u0438 \u043f\u0440\u0438\u0434\u043e\u043d\u0435\u0441\u0443\u0432\u0430 \u0437\u0430 \u043f\u043e\u0434\u0438\u0433\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442. Bloom \u0435 \u043c\u0430\u043b \u0431\u0438\u0437\u043d\u0438\u0441 \u043a\u043e\u0458 \u0435 \u043e\u0441\u043d\u043e\u0432\u0430\u043d \u043f\u0440\u0435\u0434 \u043f\u0435\u0442 \u0433\u043e\u0434\u0438\u043d\u0438, \u0432\u043e \u043a\u043e\u0458 \u0440\u0430\u0447\u043d\u043e \u0441\u0435 \u0438\u0437\u0440\u0430\u0431\u043e\u0442\u0443\u0432\u0430 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u0430, \u0432\u0435\u0433\u0430\u043d\u0441\u043a\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u043a\u043e\u0458\u0430 \u0434\u043e\u0430\u0433\u0430 \u0432\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430 \u0430\u043c\u0431\u0430\u043b\u0430\u0436\u0430. \u00a0\u041d\u0438\u0432\u043d\u0430\u0442\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u0435 \u0441\u043e\u0437\u0434\u0430\u0434\u0435\u043d\u0430 \u043e\u0434 \u0432\u0438\u0441\u043e\u043a\u043e\u043a\u0432\u0430\u043b\u0438\u0442\u0435\u0442\u043d\u0438 \u043c\u0430\u0441\u043b\u0430 \u0438 \u043f\u0443\u0442\u0435\u0440\u0438, \u0437\u0431\u043e\u0433\u0430\u0442\u0435\u043d\u0438 \u0441\u043e \u0447\u0438\u0441\u0442\u0438 \u0435\u0441\u0435\u043d\u0446\u0438\u0458\u0430\u043b\u043d\u0438 \u043c\u0430\u0441\u043b\u0430 \u0438 \u0441\u0435 \u0433\u0440\u0438\u0436\u0438 \u0437\u0430 \u043d\u0435\u0433\u0430 \u0438 \u043f\u043e\u0442\u0445\u0440\u0430\u043d\u0430 \u043d\u0430 \u0432\u0430\u0448\u0430\u0442\u0430 \u043a\u043e\u0436\u0430.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Spotify Embed: #40 Tamara Ristoska invites Bloom\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6NJ2Z6v6P9WhN6zUzBInR5?si=NWw1cPSwSbWLvyzk7l9SjQ&#038;utm_source=oembed\"><\/iframe><\/p>\n","protected":false},"featured_media":21854,"template":"","class_list":["post-21853","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#40 Tamara Ristoska invites Bloom - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#40 Tamara Ristoska invites Bloom - Europe House\" \/>\n<meta property=\"og:description\" content=\"\u0410\u043d\u0434\u0440\u0438\u0458\u0430\u043d\u0430 \u0438 \u0411\u0438\u0441\u0435\u0440\u0430 \u0441\u0435 \u0434\u0435\u0432\u043e\u0458\u043a\u0438\u0442\u0435 \u043a\u043e\u0438 \u043e\u0434 \u0438\u0434\u0435\u0458\u0430 \u0441\u043e\u0437\u0434\u0430\u0434\u043e\u0430 \u043f\u0440\u0438\u043a\u0430\u0437\u043d\u0430 \u043a\u043e\u0458\u0430 \u0432\u043b\u0438\u0458\u0430\u0435 \u0438 \u043f\u0440\u0438\u0434\u043e\u043d\u0435\u0441\u0443\u0432\u0430 \u0437\u0430 \u043f\u043e\u0434\u0438\u0433\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442. Bloom \u0435 \u043c\u0430\u043b \u0431\u0438\u0437\u043d\u0438\u0441 \u043a\u043e\u0458 \u0435 \u043e\u0441\u043d\u043e\u0432\u0430\u043d \u043f\u0440\u0435\u0434 \u043f\u0435\u0442 \u0433\u043e\u0434\u0438\u043d\u0438, \u0432\u043e \u043a\u043e\u0458 \u0440\u0430\u0447\u043d\u043e \u0441\u0435 \u0438\u0437\u0440\u0430\u0431\u043e\u0442\u0443\u0432\u0430 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u0430, \u0432\u0435\u0433\u0430\u043d\u0441\u043a\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u043a\u043e\u0458\u0430 \u0434\u043e\u0430\u0433\u0430 \u0432\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430 \u0430\u043c\u0431\u0430\u043b\u0430\u0436\u0430. \u00a0\u041d\u0438\u0432\u043d\u0430\u0442\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u0435 \u0441\u043e\u0437\u0434\u0430\u0434\u0435\u043d\u0430 \u043e\u0434 \u0432\u0438\u0441\u043e\u043a\u043e\u043a\u0432\u0430\u043b\u0438\u0442\u0435\u0442\u043d\u0438 \u043c\u0430\u0441\u043b\u0430 \u0438 \u043f\u0443\u0442\u0435\u0440\u0438, \u0437\u0431\u043e\u0433\u0430\u0442\u0435\u043d\u0438 \u0441\u043e \u0447\u0438\u0441\u0442\u0438 \u0435\u0441\u0435\u043d\u0446\u0438\u0458\u0430\u043b\u043d\u0438 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-28T15:05:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/\",\"url\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/\",\"name\":\"#40 Tamara Ristoska invites Bloom - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg\",\"datePublished\":\"2023-02-27T15:02:46+00:00\",\"dateModified\":\"2023-02-28T15:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Podcasts\",\"item\":\"https:\/\/europehouse.mkmk\/podcast\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#40 Tamara Ristoska invites Bloom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#40 Tamara Ristoska invites Bloom - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/","og_locale":"en_US","og_type":"article","og_title":"#40 Tamara Ristoska invites Bloom - Europe House","og_description":"\u0410\u043d\u0434\u0440\u0438\u0458\u0430\u043d\u0430 \u0438 \u0411\u0438\u0441\u0435\u0440\u0430 \u0441\u0435 \u0434\u0435\u0432\u043e\u0458\u043a\u0438\u0442\u0435 \u043a\u043e\u0438 \u043e\u0434 \u0438\u0434\u0435\u0458\u0430 \u0441\u043e\u0437\u0434\u0430\u0434\u043e\u0430 \u043f\u0440\u0438\u043a\u0430\u0437\u043d\u0430 \u043a\u043e\u0458\u0430 \u0432\u043b\u0438\u0458\u0430\u0435 \u0438 \u043f\u0440\u0438\u0434\u043e\u043d\u0435\u0441\u0443\u0432\u0430 \u0437\u0430 \u043f\u043e\u0434\u0438\u0433\u043d\u0443\u0432\u0430\u045a\u0435 \u043d\u0430 \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442. Bloom \u0435 \u043c\u0430\u043b \u0431\u0438\u0437\u043d\u0438\u0441 \u043a\u043e\u0458 \u0435 \u043e\u0441\u043d\u043e\u0432\u0430\u043d \u043f\u0440\u0435\u0434 \u043f\u0435\u0442 \u0433\u043e\u0434\u0438\u043d\u0438, \u0432\u043e \u043a\u043e\u0458 \u0440\u0430\u0447\u043d\u043e \u0441\u0435 \u0438\u0437\u0440\u0430\u0431\u043e\u0442\u0443\u0432\u0430 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u0430, \u0432\u0435\u0433\u0430\u043d\u0441\u043a\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u043a\u043e\u0458\u0430 \u0434\u043e\u0430\u0433\u0430 \u0432\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430 \u0430\u043c\u0431\u0430\u043b\u0430\u0436\u0430. \u00a0\u041d\u0438\u0432\u043d\u0430\u0442\u0430 \u043a\u043e\u0437\u043c\u0435\u0442\u0438\u043a\u0430 \u0435 \u0441\u043e\u0437\u0434\u0430\u0434\u0435\u043d\u0430 \u043e\u0434 \u0432\u0438\u0441\u043e\u043a\u043e\u043a\u0432\u0430\u043b\u0438\u0442\u0435\u0442\u043d\u0438 \u043c\u0430\u0441\u043b\u0430 \u0438 \u043f\u0443\u0442\u0435\u0440\u0438, \u0437\u0431\u043e\u0433\u0430\u0442\u0435\u043d\u0438 \u0441\u043e \u0447\u0438\u0441\u0442\u0438 \u0435\u0441\u0435\u043d\u0446\u0438\u0458\u0430\u043b\u043d\u0438 [&hellip;]","og_url":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/","og_site_name":"Europe House","article_modified_time":"2023-02-28T15:05:34+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/","url":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/","name":"#40 Tamara Ristoska invites Bloom - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg","datePublished":"2023-02-27T15:02:46+00:00","dateModified":"2023-02-28T15:05:34+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2023\/02\/EUH-podcast-guest-Bloom.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mkpodcast\/40-tamara-risteska-invites-bloom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Podcasts","item":"https:\/\/europehouse.mkmk\/podcast\/"},{"@type":"ListItem","position":2,"name":"#40 Tamara Ristoska invites Bloom"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/podcast\/21853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/podcast"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/21854"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=21853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}