{"id":45655,"date":"2024-09-11T10:41:57","date_gmt":"2024-09-11T10:41:57","guid":{"rendered":"https:\/\/euhouse.mk\/?page_id=45655"},"modified":"2024-09-11T10:43:04","modified_gmt":"2024-09-11T10:43:04","slug":"offices","status":"publish","type":"page","link":"https:\/\/europehouse.mk\/en\/offices\/","title":{"rendered":"Offices"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":28,"comment_status":"closed","ping_status":"closed","template":"page-templates\/offices.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-45655","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offices - Europe House<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offices - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkoffices\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T10:43:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkoffices\/\",\"url\":\"https:\/\/europehouse.mkoffices\/\",\"name\":\"Offices - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"datePublished\":\"2024-09-11T10:41:57+00:00\",\"dateModified\":\"2024-09-11T10:43:04+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkoffices\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offices - Europe House","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Offices - Europe House","og_url":"https:\/\/europehouse.mkoffices\/","og_site_name":"Europe House","article_modified_time":"2024-09-11T10:43:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkoffices\/","url":"https:\/\/europehouse.mkoffices\/","name":"Offices - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"datePublished":"2024-09-11T10:41:57+00:00","dateModified":"2024-09-11T10:43:04+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkoffices\/"]}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/pages\/45655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/comments?post=45655"}],"version-history":[{"count":1,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/pages\/45655\/revisions"}],"predecessor-version":[{"id":45656,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/pages\/45655\/revisions\/45656"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=45655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}