{"id":59947,"date":"2025-07-25T10:05:42","date_gmt":"2025-07-25T10:05:42","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=59947"},"modified":"2025-07-25T10:05:42","modified_gmt":"2025-07-25T10:05:42","slug":"youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/","title":{"rendered":"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e"},"content":{"rendered":"","protected":false},"featured_media":59963,"template":"","class_list":["post-59947","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-\u0441\u043e-europe-house-\u0432\u043e-\u043a\u0440\u0430\u0442\u043e\u0432\u043e\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-\u0441\u043e-europe-house-\u0432\u043e-\u043a\u0440\u0430\u0442\u043e\u0432\u043e\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/\",\"name\":\"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg\",\"datePublished\":\"2025-07-25T10:05:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-\u0441\u043e-europe-house-\u0432\u043e-\u043a\u0440\u0430\u0442\u043e\u0432\u043e\/","og_locale":"en_US","og_type":"article","og_title":"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-\u0441\u043e-europe-house-\u0432\u043e-\u043a\u0440\u0430\u0442\u043e\u0432\u043e\/","og_site_name":"Europe House","og_image":[{"width":1440,"height":960,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/","name":"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg","datePublished":"2025-07-25T10:05:42+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/07\/518291360_727547960035292_1850869025886472106_n-1.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/youth-skills-day-%d1%81%d0%be-europe-house-%d0%b2%d0%be-%d0%ba%d1%80%d0%b0%d1%82%d0%be%d0%b2%d0%be\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Youth Skills Day \u0441\u043e Europe House \u0432\u043e \u041a\u0440\u0430\u0442\u043e\u0432\u043e"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/59947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/59963"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=59947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}