{"id":5968,"date":"2021-04-22T11:12:11","date_gmt":"2021-04-22T11:12:11","guid":{"rendered":"https:\/\/www.euhouse.mk\/?p=2151"},"modified":"2021-04-22T11:12:11","modified_gmt":"2021-04-22T11:12:11","slug":"marking-of-earth-day-in-europe-house-kriva-palanka","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/","title":{"rendered":"Marking of Earth Day in Europe House Kriva Palanka"},"content":{"rendered":"<p>\u0412\u043e \u0447\u0435\u0441\u0442 \u043d\u0430 \u0421\u0432\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u0414\u0435\u043d \u043d\u0430 \u041f\u043b\u0430\u043d\u0435\u0442\u0430\u0442\u0430 \u0417\u0435\u043c\u0458\u0430, \u0441\u0435 \u043e\u0434\u0436\u0440\u0430 \u0430\u043a\u0446\u0438\u0458\u0430\u0442\u0430 \u201ePlant your future\u201c &#8211; \u0437\u0430\u0441\u0430\u0434\u0443\u0432\u0430\u045a\u0435 \u0446\u0432\u0435\u045c\u0438\u045a\u0430 \u0432\u043e \u0434\u0432\u043e\u0440\u043e\u0442 \u043d\u0430 Europe House \u0432\u043e \u041a\u0440\u0438\u0432\u0430 \u041f\u0430\u043b\u0430\u043d\u043a\u0430 \u0438 \u0415\u043a\u043e \u043enline \u043f\u0440\u0435\u0434\u0438\u0437\u0432\u0438\u043a.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fskp1-1.fna.fbcdn.net\/v\/t1.6435-9\/177306807_4139899726071993_5827821231580752644_n.jpg?_nc_cat=101&amp;ccb=1-3&amp;_nc_sid=730e14&amp;_nc_ohc=M4FotQD_s5QAX8AKGRI&amp;_nc_oc=AQmtlrDsss3Whnywk9Gm4HpeAhPdMSKgyYFGHXKCkk0K_dyCFvo5FqURCJt8xqGGDeo&amp;_nc_ht=scontent.fskp1-1.fna&amp;oh=241deee7b15b6d7e45a034abc969e89d&amp;oe=60A9F568\" alt=\"May be an image of tree\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fskp1-1.fna.fbcdn.net\/v\/t1.6435-9\/176417657_4139899742738658_6919051710982453507_n.jpg?_nc_cat=110&amp;ccb=1-3&amp;_nc_sid=730e14&amp;_nc_ohc=0enavARIoPUAX-gkyQH&amp;_nc_ht=scontent.fskp1-1.fna&amp;oh=7b89ef2a9772085a111a91c48d52aab7&amp;oe=60A71BEF\" alt=\"May be an image of flower and outdoors\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fskp1-1.fna.fbcdn.net\/v\/t1.6435-9\/177236286_4140374759357823_8808836499266417248_n.jpg?_nc_cat=109&amp;ccb=1-3&amp;_nc_sid=730e14&amp;_nc_ohc=_29TjiYN-ZYAX9Axp1j&amp;_nc_ht=scontent.fskp1-1.fna&amp;oh=8cca87c9b16bacbc0b53c22d68fc38d4&amp;oe=60A94648\" alt=\"May be an image of 1 person, standing, flower and outdoors\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fskp1-1.fna.fbcdn.net\/v\/t1.6435-9\/176986770_4140582792670353_2982796930831325089_n.jpg?_nc_cat=103&amp;ccb=1-3&amp;_nc_sid=730e14&amp;_nc_ohc=hNIAH6MdFcoAX_Phy7S&amp;_nc_ht=scontent.fskp1-1.fna&amp;oh=10425158b7b00bb492bb6735034f7772&amp;oe=60A74E82\" alt=\"May be an image of one or more people, people standing and outdoors\" \/><\/p>\n","protected":false},"featured_media":2152,"template":"","class_list":["post-5968","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marking of Earth Day in Europe House Kriva Palanka - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marking of Earth Day in Europe House Kriva Palanka - Europe House\" \/>\n<meta property=\"og:description\" content=\"\u0412\u043e \u0447\u0435\u0441\u0442 \u043d\u0430 \u0421\u0432\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u0414\u0435\u043d \u043d\u0430 \u041f\u043b\u0430\u043d\u0435\u0442\u0430\u0442\u0430 \u0417\u0435\u043c\u0458\u0430, \u0441\u0435 \u043e\u0434\u0436\u0440\u0430 \u0430\u043a\u0446\u0438\u0458\u0430\u0442\u0430 \u201ePlant your future\u201c &#8211; \u0437\u0430\u0441\u0430\u0434\u0443\u0432\u0430\u045a\u0435 \u0446\u0432\u0435\u045c\u0438\u045a\u0430 \u0432\u043e \u0434\u0432\u043e\u0440\u043e\u0442 \u043d\u0430 Europe House \u0432\u043e \u041a\u0440\u0438\u0432\u0430 \u041f\u0430\u043b\u0430\u043d\u043a\u0430 \u0438 \u0415\u043a\u043e \u043enline \u043f\u0440\u0435\u0434\u0438\u0437\u0432\u0438\u043a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2021\/04\/earth-day.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/\",\"url\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/\",\"name\":\"Marking of Earth Day in Europe House Kriva Palanka - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg\",\"datePublished\":\"2021-04-22T11:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg\",\"width\":1125,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marking of Earth Day in Europe House Kriva Palanka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marking of Earth Day in Europe House Kriva Palanka - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/","og_locale":"en_US","og_type":"article","og_title":"Marking of Earth Day in Europe House Kriva Palanka - Europe House","og_description":"\u0412\u043e \u0447\u0435\u0441\u0442 \u043d\u0430 \u0421\u0432\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u0414\u0435\u043d \u043d\u0430 \u041f\u043b\u0430\u043d\u0435\u0442\u0430\u0442\u0430 \u0417\u0435\u043c\u0458\u0430, \u0441\u0435 \u043e\u0434\u0436\u0440\u0430 \u0430\u043a\u0446\u0438\u0458\u0430\u0442\u0430 \u201ePlant your future\u201c &#8211; \u0437\u0430\u0441\u0430\u0434\u0443\u0432\u0430\u045a\u0435 \u0446\u0432\u0435\u045c\u0438\u045a\u0430 \u0432\u043e \u0434\u0432\u043e\u0440\u043e\u0442 \u043d\u0430 Europe House \u0432\u043e \u041a\u0440\u0438\u0432\u0430 \u041f\u0430\u043b\u0430\u043d\u043a\u0430 \u0438 \u0415\u043a\u043e \u043enline \u043f\u0440\u0435\u0434\u0438\u0437\u0432\u0438\u043a.","og_url":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/","og_site_name":"Europe House","og_image":[{"width":1125,"height":2000,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2021\/04\/earth-day.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/","url":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/","name":"Marking of Earth Day in Europe House Kriva Palanka - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg","datePublished":"2021-04-22T11:12:11+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2021\/04\/earth-day.jpeg","width":1125,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mkgallery\/marking-of-earth-day-in-europe-house-kriva-palanka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Marking of Earth Day in Europe House Kriva Palanka"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/5968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/2152"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=5968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}