{"id":5936,"date":"2020-01-23T09:32:18","date_gmt":"2020-01-23T09:32:18","guid":{"rendered":"http:\/\/superhost.com.mk\/euhouse\/?p=201"},"modified":"2020-01-23T09:32:18","modified_gmt":"2020-01-23T09:32:18","slug":"fashion-revolution-screening-of-docu-film-river-blue","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/fashion-revolution-screening-of-docu-film-river-blue\/","title":{"rendered":"Fashion Revolution &#8211; Screening of docu film &#8220;River Blue&#8221;"},"content":{"rendered":"<p>Screening of the documentary film &#8220;River Blue&#8221; (2016)<\/p>\n<p>*Topic &#8211; Negative impact of the fashion industry on the environment.<\/p>\n<p>Organizer: Fashion Revolution<\/p>\n<div id='gallery-1' class='gallery galleryid-5936 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1-576x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1-576x1024.jpg 576w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1-169x300.jpg 169w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1-768x1365.jpg 768w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg 828w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/2.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/2-300x225.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/2-768x576.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/5.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/5.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/5.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/5-300x225.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/5-768x576.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"featured_media":206,"template":"","class_list":["post-5936","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fashion Revolution - Screening of docu film &quot;River Blue&quot; - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fashion Revolution - Screening of docu film &quot;River Blue&quot; - Europe House\" \/>\n<meta property=\"og:description\" content=\"Screening of the documentary film &#8220;River Blue&#8221; (2016) *Topic &#8211; Negative impact of the fashion industry on the environment. Organizer: Fashion Revolution\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"1472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/\",\"url\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/\",\"name\":\"Fashion Revolution - Screening of docu film \\\"River Blue\\\" - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg\",\"datePublished\":\"2020-01-23T09:32:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg\",\"width\":828,\"height\":1472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fashion Revolution &#8211; Screening of docu film &#8220;River Blue&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fashion Revolution - Screening of docu film \"River Blue\" - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/","og_locale":"en_US","og_type":"article","og_title":"Fashion Revolution - Screening of docu film \"River Blue\" - Europe House","og_description":"Screening of the documentary film &#8220;River Blue&#8221; (2016) *Topic &#8211; Negative impact of the fashion industry on the environment. Organizer: Fashion Revolution","og_url":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/","og_site_name":"Europe House","og_image":[{"width":828,"height":1472,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/","url":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/","name":"Fashion Revolution - Screening of docu film \"River Blue\" - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg","datePublished":"2020-01-23T09:32:18+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/1.jpg","width":828,"height":1472},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mkgallery\/fashion-revolution-screening-of-docu-film-river-blue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Fashion Revolution &#8211; Screening of docu film &#8220;River Blue&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/5936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/206"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=5936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}