{"id":5932,"date":"2020-01-17T08:56:04","date_gmt":"2020-01-17T08:56:04","guid":{"rendered":"http:\/\/superhost.com.mk\/euhouse\/?p=1"},"modified":"2020-01-17T08:56:04","modified_gmt":"2020-01-17T08:56:04","slug":"digital-marketing-introduction-to-facebook-ads-creativ-hub","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/","title":{"rendered":"Digital Marketing &#8211; Introduction to Facebook Ads (Creative Hub)"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-5932 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o-300x199.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o-768x510.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82323240_771888143307237_7584988858362626048_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82323240_771888143307237_7584988858362626048_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82323240_771888143307237_7584988858362626048_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82323240_771888143307237_7584988858362626048_o-300x199.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82323240_771888143307237_7584988858362626048_o-768x510.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82372749_771888643307187_4919375018791534592_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82372749_771888643307187_4919375018791534592_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82372749_771888643307187_4919375018791534592_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82372749_771888643307187_4919375018791534592_o-300x199.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82372749_771888643307187_4919375018791534592_o-768x510.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82512375_771887699973948_6499581404970483712_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82512375_771887699973948_6499581404970483712_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82512375_771887699973948_6499581404970483712_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82512375_771887699973948_6499581404970483712_o-300x199.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82512375_771887699973948_6499581404970483712_o-768x510.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82590819_771888476640537_3132613029598855168_o.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82590819_771888476640537_3132613029598855168_o.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82590819_771888476640537_3132613029598855168_o.jpg 1000w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82590819_771888476640537_3132613029598855168_o-300x199.jpg 300w, https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82590819_771888476640537_3132613029598855168_o-768x510.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"featured_media":92,"template":"","class_list":["post-5932","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/\",\"url\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/\",\"name\":\"Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg\",\"datePublished\":\"2020-01-17T08:56:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg\",\"width\":1000,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital Marketing &#8211; Introduction to Facebook Ads (Creative Hub)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/","og_locale":"en_US","og_type":"article","og_title":"Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House","og_url":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/","og_site_name":"Europe House","og_image":[{"width":1000,"height":664,"url":"https:\/\/europehouse.mkwp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/","url":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/","name":"Digital Marketing - Introduction to Facebook Ads (Creative Hub) - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg","datePublished":"2020-01-17T08:56:04+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2020\/01\/82637300_771887603307291_6173491179867340800_o.jpg","width":1000,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mkgallery\/digital-marketing-introduction-to-facebook-ads-creativ-hub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Digital Marketing &#8211; Introduction to Facebook Ads (Creative Hub)"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/5932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=5932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}