{"id":59241,"date":"2025-06-27T19:20:32","date_gmt":"2025-06-27T19:20:32","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=59241"},"modified":"2025-06-27T19:20:32","modified_gmt":"2025-06-27T19:20:32","slug":"%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/","title":{"rendered":"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430"},"content":{"rendered":"","protected":false},"featured_media":59281,"template":"","class_list":["post-59241","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0448\u0432\u0435\u0434\u0441\u043a\u0430-\u0435\u0443-\u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430-\u0432\u043e-\u043a\u043e\u0447\u0430\u043d\u0438-\u0437\u0430-\u043f\u043e\u0434\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0448\u0432\u0435\u0434\u0441\u043a\u0430-\u0435\u0443-\u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430-\u0432\u043e-\u043a\u043e\u0447\u0430\u043d\u0438-\u0437\u0430-\u043f\u043e\u0434\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/\",\"name\":\"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg\",\"datePublished\":\"2025-06-27T19:20:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/\u0448\u0432\u0435\u0434\u0441\u043a\u0430-\u0435\u0443-\u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430-\u0432\u043e-\u043a\u043e\u0447\u0430\u043d\u0438-\u0437\u0430-\u043f\u043e\u0434\/","og_locale":"en_US","og_type":"article","og_title":"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/\u0448\u0432\u0435\u0434\u0441\u043a\u0430-\u0435\u0443-\u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430-\u0432\u043e-\u043a\u043e\u0447\u0430\u043d\u0438-\u0437\u0430-\u043f\u043e\u0434\/","og_site_name":"Europe House","og_image":[{"width":2048,"height":1366,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/","name":"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430 - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg","datePublished":"2025-06-27T19:20:32+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/508833301_1150769953760641_6903076601156143919_n.jpg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%88%d0%b2%d0%b5%d0%b4%d1%81%d0%ba%d0%b0-%d0%b5%d1%83-%d0%b4%d0%b5%d0%bb%d0%b5%d0%b3%d0%b0%d1%86%d0%b8%d1%98%d0%b0-%d0%b2%d0%be-%d0%ba%d0%be%d1%87%d0%b0%d0%bd%d0%b8-%d0%b7%d0%b0-%d0%bf%d0%be%d0%b4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"\u0428\u0432\u0435\u0434\u0441\u043a\u0430 \u0415\u0423 \u0434\u0435\u043b\u0435\u0433\u0430\u0446\u0438\u0458\u0430 \u0432\u043e \u041a\u043e\u0447\u0430\u043d\u0438 \u0437\u0430 \u043f\u043e\u0434\u0434\u0440\u0448\u043a\u0430 \u0438 \u0441\u043e\u043b\u0438\u0434\u0430\u0440\u043d\u043e\u0441\u0442 \u0442\u0440\u0430\u0433\u0435\u0434\u0438\u0458\u0430\u0442\u0430"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/59241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/59281"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=59241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}