{"id":58707,"date":"2025-06-18T11:08:54","date_gmt":"2025-06-18T11:08:54","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=58707"},"modified":"2025-06-18T11:08:54","modified_gmt":"2025-06-18T11:08:54","slug":"europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/","title":{"rendered":"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442!"},"content":{"rendered":"","protected":false},"featured_media":58732,"template":"","class_list":["post-58707","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-\u0441\u0442\u0440\u0443\u043c\u0438\u0446\u0430-\u0440\u0435-\u0430\u0440\u0442-\u043c\u0430\u043b\u0438-\u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-\u0441\u0442\u0440\u0443\u043c\u0438\u0446\u0430-\u0440\u0435-\u0430\u0440\u0442-\u043c\u0430\u043b\u0438-\u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/\",\"name\":\"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg\",\"datePublished\":\"2025-06-18T11:08:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-\u0441\u0442\u0440\u0443\u043c\u0438\u0446\u0430-\u0440\u0435-\u0430\u0440\u0442-\u043c\u0430\u043b\u0438-\u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438\/","og_locale":"en_US","og_type":"article","og_title":"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-\u0441\u0442\u0440\u0443\u043c\u0438\u0446\u0430-\u0440\u0435-\u0430\u0440\u0442-\u043c\u0430\u043b\u0438-\u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438\/","og_site_name":"Europe House","og_image":[{"width":2048,"height":1365,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/","name":"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442! - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg","datePublished":"2025-06-18T11:08:54+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/505132862_741101964934804_5776763837137108135_n.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/europe-house-%d1%81%d1%82%d1%80%d1%83%d0%bc%d0%b8%d1%86%d0%b0-%d1%80%d0%b5-%d0%b0%d1%80%d1%82-%d0%bc%d0%b0%d0%bb%d0%b8-%d1%80%d0%b5%d1%86%d0%b8%d0%ba%d0%bb%d0%b0%d1%82%d0%be%d1%80%d0%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"Europe House \u0421\u0442\u0440\u0443\u043c\u0438\u0446\u0430: \u201e\u0420\u0415-\u0410\u0420\u0422, \u041c\u0430\u043b\u0438 \u0440\u0435\u0446\u0438\u043a\u043b\u0430\u0442\u043e\u0440\u0438, \u0433\u043e\u043b\u0435\u043c\u0438 \u043a\u0440\u0435\u0430\u0442\u043e\u0440\u0438\u201c \u2013 \u0438\u0437\u043b\u043e\u0436\u0431\u0430 \u0448\u0442\u043e \u0433\u043e \u0441\u043f\u043e\u0438 \u0434\u0435\u0442\u0441\u043a\u0438\u043e\u0442 \u043a\u0440\u0435\u0430\u0442\u0438\u0432\u0435\u043d \u0434\u0443\u0445 \u0441\u043e \u0435\u043a\u043e\u043b\u043e\u0448\u043a\u0430\u0442\u0430 \u0441\u0432\u0435\u0441\u0442!"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/58707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/58732"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=58707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}