{"id":58225,"date":"2025-06-07T07:13:21","date_gmt":"2025-06-07T07:13:21","guid":{"rendered":"https:\/\/europehouse.mk\/?post_type=gallery&#038;p=58225"},"modified":"2025-06-07T07:13:21","modified_gmt":"2025-06-07T07:13:21","slug":"%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba","status":"publish","type":"gallery","link":"https:\/\/europehouse.mk\/en\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/","title":{"rendered":"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a!"},"content":{"rendered":"","protected":false},"featured_media":58235,"template":"","class_list":["post-58225","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0441\u0438\u0442\u0435-\u043d\u0430-\u0442\u043e\u0447\u0430\u043a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europehouse.mk\/mk\/gallery\/\u0441\u0438\u0442\u0435-\u043d\u0430-\u0442\u043e\u0447\u0430\u043a\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe House\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/\",\"url\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/\",\"name\":\"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House\",\"isPartOf\":{\"@id\":\"https:\/\/europehouse.mk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg\",\"datePublished\":\"2025-06-07T07:13:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Galleries\",\"item\":\"https:\/\/europehouse.mkmk\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europehouse.mk\/#website\",\"url\":\"https:\/\/europehouse.mk\/\",\"name\":\"Europe House\",\"description\":\"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435\",\"publisher\":{\"@id\":\"https:\/\/europehouse.mk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europehouse.mk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europehouse.mk\/#organization\",\"name\":\"Europe House\",\"url\":\"https:\/\/europehouse.mk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"contentUrl\":\"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg\",\"width\":2246,\"height\":620,\"caption\":\"Europe House\"},\"image\":{\"@id\":\"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europehouse.mk\/mk\/gallery\/\u0441\u0438\u0442\u0435-\u043d\u0430-\u0442\u043e\u0447\u0430\u043a\/","og_locale":"en_US","og_type":"article","og_title":"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House","og_url":"https:\/\/europehouse.mk\/mk\/gallery\/\u0441\u0438\u0442\u0435-\u043d\u0430-\u0442\u043e\u0447\u0430\u043a\/","og_site_name":"Europe House","og_image":[{"width":2048,"height":1365,"url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/","url":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/","name":"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a! - Europe House","isPartOf":{"@id":"https:\/\/europehouse.mk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage"},"image":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage"},"thumbnailUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg","datePublished":"2025-06-07T07:13:21+00:00","breadcrumb":{"@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#primaryimage","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/06\/503824882_1138353471668956_820335469001562752_n.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/europehouse.mk\/mk\/gallery\/%d1%81%d0%b8%d1%82%d0%b5-%d0%bd%d0%b0-%d1%82%d0%be%d1%87%d0%b0%d0%ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Galleries","item":"https:\/\/europehouse.mkmk\/gallery\/"},{"@type":"ListItem","position":2,"name":"\u0421\u0438\u0442\u0435 \u043d\u0430 \u0442\u043e\u0447\u0430\u043a!"}]},{"@type":"WebSite","@id":"https:\/\/europehouse.mk\/#website","url":"https:\/\/europehouse.mk\/","name":"Europe House","description":"\u0422\u0443\u043a\u0430 \u0437\u0430 \u043c\u043b\u0430\u0434\u0438\u0442\u0435","publisher":{"@id":"https:\/\/europehouse.mk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europehouse.mk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europehouse.mk\/#organization","name":"Europe House","url":"https:\/\/europehouse.mk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/","url":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","contentUrl":"https:\/\/europehouse.mk\/wp-content\/uploads\/2025\/11\/cropped-EUROPE-HOUSE-FB-Profile-Picture-redisign-1-1.jpg","width":2246,"height":620,"caption":"Europe House"},"image":{"@id":"https:\/\/europehouse.mk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery\/58225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media\/58235"}],"wp:attachment":[{"href":"https:\/\/europehouse.mk\/en\/wp-json\/wp\/v2\/media?parent=58225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}